{"id":74,"date":"2024-07-10T12:50:20","date_gmt":"2024-07-10T15:50:20","guid":{"rendered":"https:\/\/hridiomas.com\/aprender-mandarim\/?p=74"},"modified":"2025-03-24T12:21:26","modified_gmt":"2025-03-24T15:21:26","slug":"palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender","status":"publish","type":"post","link":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/","title":{"rendered":"Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Acredite! Aprender o b\u00e1sico de chin\u00eas mandarim pode ser um desafio, mas n\u00e3o \u00e9 imposs\u00edvel. Algumas palavras b\u00e1sicas ajudar\u00e3o voc\u00ea a deixar de ser um completo iniciante e conseguir at\u00e9 manter conversas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea est\u00e1 planejando uma viagem \u00e0 China, procurando expandir seus horizontes culturais ou simplesmente desejando se desafiar com um novo idioma, aprender algumas palavras e frases b\u00e1sicas em chin\u00eas mandarim \u00e9 um excelente ponto de partida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explicaremos aqui algumas das palavras em chin\u00eas mais utilizadas que voc\u00ea encontrar\u00e1 em quase todos os textos ou conversas no idioma. Voc\u00ea tamb\u00e9m aprender\u00e1 algumas coisas que os estudantes iniciantes de chin\u00eas devem saber sobre o idioma: tons, escrita e forma\u00e7\u00e3o de palavras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-palavras-e-frases-essenciais-em-chines\">Palavras e frases essenciais em chin\u00eas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos come\u00e7ar com algumas das mais importantes palavras em chin\u00eas com tradu\u00e7\u00e3o. Apresentaremos primeiro a palavra em portugu\u00eas, seguida dos caracteres chineses e, por fim, a pron\u00fancia <em>pinyin <\/em>entre par\u00eanteses.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pronomes-em-chines\">Pronomes em chin\u00eas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os falantes de mandarim deixam de usar os pronomes se for \u00f3bvia a pessoa de quem est\u00e3o falando. Mas eles s\u00e3o utilizados para dar \u00eanfase. Como estudante, \u00e9 \u00fatil utilizar os pronomes corretos enquanto voc\u00ea fala. Isso ajuda a garantir que voc\u00ea estruture bem suas frases.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-eu-mim-\u6211-w\u01d2\">Eu\/mim &#8211; \u6211 (w\u01d2)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para &#8220;eu&#8221; ou &#8220;mim&#8221;, utiliza-se o pronome <strong>\u6211<\/strong> (w\u01d2). Diferentemente de algumas l\u00ednguas ocidentais, como o portugu\u00eas, o mandarim n\u00e3o distingue casos gramaticais como nominativo (eu) e acusativo (mim). Portanto, o mesmo pronome \u00e9 usado em ambas as situa\u00e7\u00f5es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-voce-\u4f60-n\u01d0\">Voc\u00ea &#8211; \u4f60 (n\u01d0)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O pronome <strong>\u4f60 <\/strong>(n\u01d0) \u00e9 usado para se dirigir a algu\u00e9m de maneira informal, como em situa\u00e7\u00f5es casuais ou entre amigos. Um exemplo comum \u00e9 a sauda\u00e7\u00e3o \u4f60\u597d (n\u01d0 h\u01ceo), que significa &#8220;ol\u00e1&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para mostrar respeito ou formalidade, como em situa\u00e7\u00f5es de neg\u00f3cios, com pessoas mais velhas ou em contextos formais, utiliza-se <strong>\u60a8<\/strong> (n\u00edn). Este \u00e9 o equivalente formal de &#8220;voc\u00ea&#8221; e demonstra cortesia adicional.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ele-ela-\u5979-\u4ed6-ta\">Ele\/ela &#8211; \u5979 \/ \u4ed6 (t\u0101)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os pronomes <strong>\u4ed6<\/strong> (t\u0101) e <strong>\u5979<\/strong> (t\u0101) t\u00eam a mesma pron\u00fancia, mas seus significados diferem dependendo do contexto. Por isso, ao ouvir algu\u00e9m falar, voc\u00ea precisar\u00e1 deduzir se a refer\u00eancia \u00e9 &#8220;ele&#8221; ou &#8220;ela&#8221; com base na conversa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por escrito, por\u00e9m, os dois pronomes possuem caracteres distintos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u4ed6<\/strong> (t\u0101): usado para &#8220;ele&#8221;.<\/li>\n\n\n\n<li><strong>\u5979<\/strong> (t\u0101): usado para &#8220;ela&#8221;.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Vale lembrar que em contextos escritos, caso o g\u00eanero n\u00e3o esteja claro ou se referir a um grupo misto, costuma-se usar <strong>\u4ed6<\/strong> (t\u0101) como forma neutra.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-formacao-do-plural\">Forma\u00e7\u00e3o do plural<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para formar o plural dos pronomes pessoais em mandarim, basta acrescentar <strong>\u4eec<\/strong> (men) ao final do pronome singular.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>N\u00f3s: <strong>\u6211\u4eec <\/strong>(w\u01d2 men)<\/li>\n\n\n\n<li>Voc\u00eas: <strong>\u4f60\u4eec <\/strong>(n\u01d0 men)<\/li>\n\n\n\n<li>Eles\/Ellas: <strong>\u4ed6\u4eec <\/strong>(t\u0101 men): usado para um grupo de homens ou um grupo misto.<\/li>\n\n\n\n<li>Ellas: <strong>\u5979\u4eec <\/strong>(t\u0101 men): usado para um grupo exclusivamente feminino.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Essa simplicidade \u00e9 uma vantagem do mandarim, j\u00e1 que n\u00e3o h\u00e1 formas irregulares.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-indicacao-de-posse\">Indica\u00e7\u00e3o de posse<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para indicar posse, acrescente <strong>\u7684<\/strong> (de) ap\u00f3s o pronome. \u00c9 semelhante ao uso do ap\u00f3strofo seguido de &#8220;s&#8221; no ingl\u00eas. Por exemplo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Meu\/minha: <strong>\u6211\u7684 <\/strong>(w\u01d2 de)<\/li>\n\n\n\n<li>Seu\/sua: <strong>\u4f60\u7684 <\/strong>(n\u01d0 de)<\/li>\n\n\n\n<li>Nosso\/nossa: <strong>\u6211\u4eec\u7684<\/strong> (w\u01d2 men de)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A part\u00edcula <strong>\u7684<\/strong> (de) tem muitas aplica\u00e7\u00f5es e \u00e9 uma das palavras mais comuns em mandarim, essencial para construir frases com clareza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-isso-e-aquilo-no-mandarim\">&#8220;Isso&#8221; e &#8220;Aquilo&#8221; no mandarim<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os pronomes demonstrativos &#8220;isso&#8221; (<strong>\u8fd9<\/strong> &#8211; zh\u00e8) e &#8220;aquilo&#8221; (<strong>\u90a3<\/strong> &#8211; n\u00e0) funcionam de maneira semelhante ao portugu\u00eas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Isso (<strong>\u8fd9<\/strong> &#8211; zh\u00e8): usado para objetos ou pessoas pr\u00f3ximas do falante.<\/li>\n\n\n\n<li>Aquilo (<strong>\u90a3<\/strong> &#8211; n\u00e0): usado para objetos ou pessoas que est\u00e3o longe do falante.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong> \u8fd9\u662f\u4e00\u4e2a\u82f9\u679c<\/strong> (zh\u00e8 sh\u00ec y\u012b g\u00e8 p\u00edng gu\u01d2)<br>Isso \u00e9 uma ma\u00e7\u00e3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u90a3\u4e2a\u4eba\u662f\u6211\u7684\u670b\u53cb<\/strong> (n\u00e0 g\u00e8 r\u00e9n sh\u00ec w\u01d2 de p\u00e9ng y\u01d2u)<br>Aquela pessoa \u00e9 meu amigo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para transformar &#8220;isso&#8221; e &#8220;aquilo&#8221; em &#8220;estes&#8221; e &#8220;aqueles&#8221;, basta acrescentar <strong>\u4e9b<\/strong> (xi\u0113) ap\u00f3s o pronome demonstrativo. Esse marcador indica plural de forma geral.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estes (<strong>\u8fd9\u4e9b <\/strong>&#8211; zh\u00e8 xi\u0113)<\/li>\n\n\n\n<li>Aqueles (<strong>\u90a3\u4e9b <\/strong>&#8211; n\u00e0 xi\u0113)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8fd9\u4e9b\u4eba\u662f\u6211\u7684\u540c\u5b66<\/strong> (zh\u00e8 xi\u0113 r\u00e9n sh\u00ec w\u01d2 de t\u00f3ng xu\u00e9)<br>Estas pessoas s\u00e3o meus colegas de classe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u90a3\u4e9b\u4e66\u662f\u4ed6\u7684<\/strong> (n\u00e0 xi\u0113 sh\u016b sh\u00ec t\u0101 de)<br>Aqueles livros s\u00e3o dele.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-palavras-interrogativas-em-chines\">Palavras interrogativas em chin\u00eas<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-o-que-\u4ec0\u4e48-shenme\">O qu\u00ea \u2013 \u4ec0\u4e48 (sh\u00e9nme)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O termo <strong>\u4ec0\u4e48 <\/strong>(sh\u00e9nme) corresponde a &#8220;o qu\u00ea&#8221; em portugu\u00eas. Ele \u00e9 usado de maneira similar, mas com maior flexibilidade na posi\u00e7\u00e3o dentro da frase.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u90a3\u662f\u4ec0\u4e48\uff1f<\/strong>(N\u00e0 sh\u00ec sh\u00e9nme?)<br>O que \u00e9 isso? (Literalmente: &#8220;Isso \u00e9 o qu\u00ea?&#8221;)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para responder, basta substituir <strong>\u4ec0\u4e48 <\/strong>(sh\u00e9nme) pela informa\u00e7\u00e3o desejada:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u90a3\u662f\u4e00\u672c\u4e66 <\/strong>(N\u00e0 sh\u00ec y\u012b b\u011bn sh\u016b)<br>Isso \u00e9 um livro.<\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background wp-block-paragraph\">A posi\u00e7\u00e3o de <strong>\u4ec0\u4e48 <\/strong>(sh\u00e9nme) na frase pode variar de acordo com a estrutura e o contexto, mas a pergunta sempre ser\u00e1 clara devido \u00e0 simplicidade gramatical do mandarim.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-quando-\u4ec0\u4e48\u65f6\u5019-shenme-shihou\">Quando \u2013 \u4ec0\u4e48\u65f6\u5019 (sh\u00e9nme sh\u00edh\u00f2u)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O termo <strong>\u4ec0\u4e48\u65f6\u5019 <\/strong>(sh\u00e9nme sh\u00edh\u00f2u) se traduz literalmente como &#8220;qual hor\u00e1rio&#8221; e \u00e9 usado para perguntar sobre o momento ou per\u00edodo em que algo ocorrer\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u4ec0\u4e48\u65f6\u5019\u53bb\u65c5\u884c<\/strong>\uff1f(N\u01d0 sh\u00e9nme sh\u00edh\u00f2u q\u00f9 l\u01dax\u00edng?)<br>Quando voc\u00ea vai viajar?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para responder, substitua <strong>\u4ec0\u4e48\u65f6\u5019<\/strong> (sh\u00e9nme sh\u00edh\u00f2u) pelo momento correspondente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u660e\u5929\u53bb\u65c5\u884c <\/strong>(W\u01d2 m\u00edngti\u0101n q\u00f9 l\u01dax\u00edng)<br>Eu vou viajar amanh\u00e3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-quantos-\u51e0-j\u01d0\">Quantos \u2013 \u51e0 (j\u01d0)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O caractere <strong>\u51e0<\/strong> (j\u01d0) \u00e9 usado para perguntar sobre pequenas quantidades ou n\u00fameros menores, geralmente at\u00e9 10. Ele \u00e9 seguido por uma unidade de medida ou classifica\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6559\u5ba4\u91cc\u6709\u51e0\u4e2a\u5b66\u751f<\/strong>\uff1f(Ji\u00e0osh\u00ec l\u01d0 y\u01d2u j\u01d0 g\u00e8 xu\u00e9sh\u0113ng?)<br>Quantos alunos est\u00e3o na sala?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6559\u5ba4\u91cc\u6709\u4e94\u4e2a\u5b66\u751f<\/strong>\u3002(Ji\u00e0osh\u00ec l\u01d0 y\u01d2u w\u01d4 g\u00e8 xu\u00e9sh\u0113ng.)<br>H\u00e1 cinco alunos na sala.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-quanto-\u591a\u5c11-duoshao\">Quanto \u2013 \u591a\u5c11 (du\u014dshao)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O termo <strong>\u591a\u5c11<\/strong> (du\u014dshao), que literalmente significa &#8220;muitos poucos&#8221;, \u00e9 usado para perguntar sobre quantidades maiores ou valores desconhecidos. \u00c9 comumente empregado para perguntar pre\u00e7os ou n\u00fameros grandes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8fd9\u4e2a\u591a\u5c11\u94b1\uff1f<\/strong>(Zh\u00e8ge du\u014dshao qi\u00e1n?)<br>Quanto custa isso?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8fd9\u4e2a\u4e8c\u5341\u5757\u94b1\u3002<\/strong>(Zh\u00e8ge \u00e8rsh\u00ed ku\u00e0i qi\u00e1n.)<br>Isso custa 20 yuans.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-quem-\u8c01-shei\">Quem \u2013 \u8c01 (sh\u00e9i)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O termo <strong>\u8c01<\/strong> (sh\u00e9i) \u00e9 usado da mesma maneira que &#8220;quem&#8221; no portugu\u00eas, para perguntar sobre pessoas espec\u00edficas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8c01\u5728\u6572\u95e8\uff1f<\/strong>(Sh\u00e9i z\u00e0i qi\u0101o m\u00e9n?)<br>Quem est\u00e1 batendo \u00e0 porta?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u662f\u6211\u7684\u670b\u53cb\u3002<\/strong>(Sh\u00ec w\u01d2 de p\u00e9ngy\u01d2u.)<br>\u00c9 meu amigo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-onde-\u54ea\u91cc-n\u01cel\u01d0\">Onde \u2013 \u54ea\u91cc (n\u01cel\u01d0)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O termo <strong>\u54ea\u91cc <\/strong>(n\u01cel\u01d0) \u00e9 usado para perguntar &#8220;onde&#8221;. O segundo caractere, <strong>\u91cc<\/strong> (l\u01d0), tamb\u00e9m pode significar &#8220;em&#8221; ou &#8220;dentro&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u5728\u54ea\u91cc\uff1f<\/strong>(N\u01d0 z\u00e0i n\u01cel\u01d0?)<br>Onde voc\u00ea est\u00e1?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u5728\u5bb6\u91cc\u3002<\/strong>(W\u01d2 z\u00e0i ji\u0101 l\u01d0.)<br>Estou em casa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-indicador-de-perguntas-de-sim-nao-\u5417-ma\">Indicador de perguntas de sim\/n\u00e3o \u2013 \u5417 (ma)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O marcador <strong>\u5417<\/strong> (ma) transforma uma frase afirmativa em uma pergunta de sim\/n\u00e3o. Ele \u00e9 simplesmente adicionado ao final da frase.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u597d\u5417\uff1f<\/strong>(N\u01d0 h\u01ceo ma?)<br>Voc\u00ea est\u00e1 bem?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u662f\u7684\uff0c\u6211\u5f88\u597d\u3002<\/strong>(Sh\u00ec de, w\u01d2 h\u011bn h\u01ceo.)<br>Sim, estou bem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4e0d\uff0c\u6211\u4e0d\u592a\u597d\u3002<\/strong>(B\u00f9, w\u01d2 b\u00f9 t\u00e0i h\u01ceo.)<br>N\u00e3o, n\u00e3o estou bem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-frases-em-chines-em-situacoes-sociais\">Frases em chin\u00eas em situa\u00e7\u00f5es sociais<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ser educado \u00e9 essencial ao aprender a falar chin\u00eas. Al\u00e9m de cumprimentar algu\u00e9m com <strong>\u4f60\u597d<\/strong> (n\u01d0 h\u01ceo) \u2013 &#8220;ol\u00e1&#8221;, estas frases \u00fateis ajudar\u00e3o em conversas b\u00e1sicas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-meu-nome-e-\u6211\u53eb-w\u01d2-jiao\">Meu nome \u00e9 \u2013 \u6211\u53eb (w\u01d2 ji\u00e0o)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u53eb<\/strong> (ji\u00e0o) significa &#8220;se chamar&#8221; e \u00e9 usado para apresentar o nome de forma simples e direta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u53eb Noreen<\/strong> (W\u01d2 ji\u00e0o Noreen)<br>Meu nome \u00e9 Noreen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se preferir ser mais formal ou usar o nome completo, voc\u00ea pode dizer:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u7684\u540d\u5b57\u662f Ana <\/strong>(W\u01d2 de m\u00edngzi sh\u00ec Ana)<br>Meu nome \u00e9 Ana.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-por-favor-\u8bf7-q\u01d0ng\">Por favor \u2013 \u8bf7 (q\u01d0ng)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A palavra <strong>\u8bf7<\/strong> (q\u01d0ng) \u00e9 usada para pedir algo de maneira educada, equivalente a &#8220;por favor&#8221; em portugu\u00eas. Ela pode ser colocada no in\u00edcio de uma frase, e tamb\u00e9m funciona como um verbo que significa &#8220;convidar&#8221; ou &#8220;pedir&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8bf7\u5750<\/strong> (Q\u01d0ng zu\u00f2)<br>Por favor, sente-se.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqui, <strong>\u5750<\/strong> (zu\u00f2) significa &#8220;sentar&#8221;. <strong>\u8bf7<\/strong> (q\u01d0ng) suaviza o pedido e torna a frase mais educada.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-desculpe-\u5bf9\u4e0d\u8d77-duibuq\u01d0\">Desculpe \u2013 \u5bf9\u4e0d\u8d77 (du\u00ecbuq\u01d0)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quando voc\u00ea deseja pedir desculpas a algu\u00e9m, use <strong>\u5bf9\u4e0d\u8d77 <\/strong>(du\u00ecbuq\u01d0), que significa &#8220;desculpe&#8221;. \u00c9 uma forma comum de expressar arrependimento em situa\u00e7\u00f5es cotidianas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u5bf9\u4e0d\u8d77\uff0c\u6211\u8fdf\u5230\u4e86<\/strong> (Du\u00ecbuq\u01d0, w\u01d2 ch\u00edd\u00e0o le)<br>Desculpe, estou atrasado. (Literalmente: &#8220;Desculpe, eu cheguei atrasado.&#8221;)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-obrigado-a-\u8c22\u8c22-xiexie\">Obrigado(a) \u2013 \u8c22\u8c22 (xi\u00e8xi\u00e8)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8c22\u8c22<\/strong> (xi\u00e8xi\u00e8) significa &#8220;obrigado(a)&#8221; e \u00e9 a forma mais comum de agradecer em chin\u00eas. Para um tom mais pessoal ou enf\u00e1tico, voc\u00ea pode adicionar <strong>\u4f60<\/strong> (n\u01d0) no final, o que torna a express\u00e3o mais direta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8c22\u8c22<\/strong> (xi\u00e8xi\u00e8)<br>Obrigado(a).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8c22\u8c22\u4f60\uff0c\u4f60\u771f\u597d<\/strong> (Xi\u00e8xi\u00e8 n\u01d0, n\u01d0 zh\u0113n h\u01ceo).<br>Muito obrigado(a), voc\u00ea \u00e9 muito gentil.<\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background wp-block-paragraph\">Nota: <strong>\u4f60<\/strong> (n\u01d0) significa &#8220;voc\u00ea&#8221;. Usar <strong>\u4f60<\/strong> depois de <strong>\u8c22\u8c22 <\/strong>transmite mais pessoalidade e carinho, similar ao &#8220;muito obrigado(a)&#8221; em portugu\u00eas. <a href=\"https:\/\/hridiomas.com\/aprender-mandarim\/como-dizer-obrigado-em-diferentes-linguas-da-china\/\">J\u00e1 falamos aqui sobre &#8220;obrigado&#8221; em diferentes l\u00ednguas da China.<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-bom-dia-\u65e9-z\u01ceo\">Bom dia \u2013 \u65e9 (z\u01ceo)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A palavra <strong>\u65e9<\/strong> (z\u01ceo) significa &#8220;manh\u00e3&#8221; e \u00e9 a maneira mais informal de cumprimentar algu\u00e9m pela manh\u00e3. \u00c9 comum entre amigos, colegas de trabalho e em contextos mais descontra\u00eddos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u65e9 (z\u01ceo)!<\/strong><br>Bom dia! (Cumprimento casual, mais usado em contextos informais.)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-bom-dia-\u65e9\u5b89-z\u01ceo-an\">Bom dia \u2013 \u65e9\u5b89 (z\u01ceo \u0101n)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u65e9\u5b89<\/strong> (z\u01ceo \u0101n) traduz-se como &#8220;paz matinal&#8221; e \u00e9 uma forma um pouco mais formal do que <strong>\u65e9<\/strong> (z\u01ceo). Usada quando voc\u00ea deseja cumprimentar algu\u00e9m de maneira mais polida, mas ainda n\u00e3o t\u00e3o formal quanto <strong>\u65e9\u4e0a\u597d<\/strong> (z\u01ceoshang h\u01ceo), n\u00edvel m\u00e1ximo de formalidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u65e9\u5b89<\/strong> (z\u01ceo \u0101n)<br>Bom dia. (formal)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-bom-dia-\u65e9\u4e0a\u597d-z\u01ceoshang-h\u01ceo\">Bom dia \u2013 \u65e9\u4e0a\u597d (z\u01ceoshang h\u01ceo)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A forma mais formal de dizer &#8220;bom dia&#8221; em mandarim \u00e9 <strong>\u65e9\u4e0a\u597d<\/strong> (z\u01ceoshang h\u01ceo). <strong>\u65e9\u4e0a<\/strong> (z\u01ceoshang) significa &#8220;manh\u00e3&#8221;, e <strong>\u597d<\/strong> (h\u01ceo) significa &#8220;bom&#8221;. Portanto, <strong>\u65e9\u4e0a\u597d<\/strong> \u00e9 um cumprimento padr\u00e3o e adequado em ambientes profissionais ou com pessoas que voc\u00ea n\u00e3o conhece bem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u65e9\u4e0a\u597d <\/strong>(z\u01ceoshang h\u01ceo)<br>Bom dia! (muito formal)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-boa-tarde-ou-boa-noite-\u665a\u4e0a\u597d-w\u01censhang-h\u01ceo\">Boa tarde ou boa noite \u2013 \u665a\u4e0a\u597d (w\u01censhang h\u01ceo)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Segue o mesmo padr\u00e3o de <strong>\u65e9\u4e0a\u597d<\/strong> (z\u01ceoshang h\u01ceo) para &#8220;bom dia&#8221;. O caractere <strong>\u665a<\/strong> (w\u01cen) significa &#8220;noite&#8221;. <strong>\u665a\u4e0a\u597d<\/strong> (w\u01censhang h\u01ceo) \u00e9 uma sauda\u00e7\u00e3o formal usada no per\u00edodo noturno, equivalente a &#8220;boa noite&#8221; no sentido de cumprimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u665a\u4e0a\u597d<\/strong> (w\u01censhang h\u01ceo)<br>Boa noite (formal)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-noite-casual-\u665a-w\u01cen\">Noite casual \u2013 \u665a (w\u01cen)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Em situa\u00e7\u00f5es informais, apenas dizer <strong>\u665a<\/strong> (w\u01cen) pode ser suficiente, especialmente em contextos descontra\u00eddos entre amigos ou familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u665a<\/strong> (w\u01cen)<br>Boa noite!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-boa-noite-como-despedida-\u665a\u5b89-w\u01cen-an\">Boa noite como despedida \u2013 \u665a\u5b89 (w\u01cen \u0101n)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u665a\u5b89 <\/strong>(w\u01cen \u0101n) \u00e9 usado para desejar boa noite quando algu\u00e9m est\u00e1 se preparando para dormir, sendo equivalente ao &#8220;boa noite&#8221; de despedida em portugu\u00eas. O caractere <strong>\u5b89<\/strong> (\u0101n) significa &#8220;paz&#8221;, ent\u00e3o <strong>\u665a\u5b89 <\/strong>pode ser traduzido como &#8220;paz noturna&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u665a\u5b89<\/strong> (w\u01cen \u0101n)<br>Boa noite (despedida)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-adeus-\u518d\u89c1-zaijian\">Adeus \u2013 \u518d\u89c1 (z\u00e0iji\u00e0n)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u518d\u89c1<\/strong> (z\u00e0iji\u00e0n) \u00e9 a forma mais comum de dizer &#8220;adeus&#8221; em chin\u00eas. Sua tradu\u00e7\u00e3o literal \u00e9 &#8220;ver-se de novo&#8221;, transmitindo um desejo de reencontro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u518d\u89c1<\/strong> (z\u00e0iji\u00e0n)<br>Adeus, at\u00e9 logo!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-principais-verbos-em-chines\">Principais verbos em chin\u00eas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Uma das vantagens dos verbos em chin\u00eas \u00e9 que eles t\u00eam apenas uma forma, o que elimina a necessidade de conjuga\u00e7\u00e3o por tempo verbal ou aspecto. Se quiser colocar um verbo no pret\u00e9rito, basta acrescentar <strong>\u4e86<\/strong> (le) ao final para mostrar que ele foi conclu\u00eddo. E, para o futuro, acrescenta-se <strong>\u4f1a <\/strong>(hu\u00ec) antes do verbo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para indicar o futuro, usamos <strong>\u4f1a<\/strong> (hu\u00ec) antes do verbo, mas \u00e9 importante lembrar que <strong>\u4f1a <\/strong>(hu\u00ec) pode tamb\u00e9m indicar habilidade ou possibilidade, dependendo do contexto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea quiser negar um verbo, deve acrescentar <strong>\u4e0d<\/strong> (b\u00f9), \u00e0 exce\u00e7\u00e3o do pr\u00f3prio verbo &#8220;ter&#8221; que possui seu pr\u00f3prio &#8220;contra-verbo&#8221;. Em mandarim existe o verbo &#8220;n\u00e3o-ter&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ser-estar-\u662f-shi\">Ser\/Estar \u2013 \u662f (sh\u00ec)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u662f<\/strong> (sh\u00ec) \u00e9 equivalente a &#8220;ser\/estar&#8221; em portugu\u00eas, mas \u00e9 usado exclusivamente para indicar identidade, origem ou equival\u00eancias diretas. Ele n\u00e3o \u00e9 usado para expressar estados tempor\u00e1rios, como &#8220;estar feliz&#8221; ou &#8220;estar cansado&#8221; (esses casos usam outros verbos ou estruturas).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u662f\u7f8e\u56fd\u4eba<\/strong> (W\u01d2 sh\u00ec m\u011bigu\u00f3 r\u00e9n)<br>Eu sou americano (literalmente: &#8220;eu sou uma pessoa americana&#8221;)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ter-\u6709-y\u01d2u\">Ter \u2013 \u6709 (y\u01d2u)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6709<\/strong> (y\u01d2u) \u00e9 um verbo essencial em chin\u00eas. Ele \u00e9 usado principalmente para expressar posse ou exist\u00eancia. Al\u00e9m disso, \u00e9 frequentemente encontrado em express\u00f5es idiom\u00e1ticas e frases gramaticais. Entre outros, pode ser usado para dizer que algo ou algu\u00e9m est\u00e1 presente ou existe em um determinado local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u7684\u5bb6\u6709\u591a\u4eba<\/strong> (W\u01d2 de ji\u0101 y\u01d2u du\u014d r\u00e9n).<br>H\u00e1 muitas pessoas na minha fam\u00edlia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para negar, usa-se <strong>\u6ca1\u6709<\/strong> (m\u00e9iy\u01d2u), que significa &#8220;n\u00e3o tem&#8221; ou &#8220;n\u00e3o h\u00e1&#8221;. A estrutura \u00e9:<br>Sujeito + \u6ca1\u6709 (m\u00e9iy\u01d2u) + Objeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u6ca1\u6709\u8f66 <\/strong>(W\u01d2 m\u00e9iy\u01d2u ch\u0113)<br>Eu n\u00e3o tenho um carro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ir-\u53bb-qu\">Ir \u2013 \u53bb (q\u00f9)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u53bb<\/strong> (q\u00f9) significa &#8220;ir&#8221; e \u00e9 usado para expressar o movimento em dire\u00e7\u00e3o a um lugar ou destino. Sua estrutura b\u00e1sica \u00e9: Sujeito + <strong>\u53bb<\/strong> (q\u00f9) + Destino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u53bb<\/strong> (q\u00f9) \u00e9 frequentemente seguido pelo lugar ou pela a\u00e7\u00e3o para onde\/algo que se pretende ir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u53bb\u90a3\u91cc<\/strong> (W\u01d2 q\u00f9 n\u00e0l\u01d0)<br>Eu vou l\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u53bb\u5b66\u6821<\/strong> (W\u01d2 q\u00f9 xu\u00e9xi\u00e0o).<br>Eu vou \u00e0 escola.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-comer-\u5403-chi\">Comer \u2013 \u5403 (ch\u012b)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u5403<\/strong> (ch\u012b) significa &#8220;comer&#8221; e \u00e9 um dos verbos mais b\u00e1sicos e importantes em chin\u00eas. Ele pode ser usado sozinho ou combinado com outros caracteres para expressar ideias relacionadas \u00e0 comida ou ao ato de comer. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A estrutura mais simples para usar <strong>\u5403<\/strong> (ch\u012b) \u00e9: Sujeito + <strong>\u5403<\/strong> (ch\u012b) + Objeto (comida).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u5403\u82f9\u679c<\/strong> (W\u01d2 ch\u012b p\u00ednggu\u01d2)<br>Eu como ma\u00e7\u00e3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se quiser dizer que algo \u00e9 saboroso, basta acrescentar <strong>\u597d<\/strong> (h\u01ceo) (bom) ao verbo para formar <strong>\u597d\u5403<\/strong> (h\u01ceo ch\u012b), ou literalmente &#8220;delicioso&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8fd9\u9053\u83dc\u5f88\u597d\u5403<\/strong> (Zh\u00e8 d\u00e0o c\u00e0i h\u011bn h\u01ceo ch\u012b).<br>Este prato \u00e9 delicioso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-beber-\u559d-he\">Beber \u2013 \u559d (h\u0113)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u559d<\/strong> (h\u0113) significa &#8220;beber&#8221; e \u00e9 usado para descrever o ato de consumir l\u00edquidos. Assim como o verbo <strong>\u5403<\/strong> (ch\u012b) (comer), ele tamb\u00e9m compartilha o radical <strong>\u53e3<\/strong> (k\u01d2u), que significa &#8220;boca&#8221;, indicando uma rela\u00e7\u00e3o com a\u00e7\u00f5es relacionadas \u00e0 ingest\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A estrutura mais simples para usar <strong>\u559d<\/strong> (h\u0113) \u00e9: Sujeito + <strong>\u559d<\/strong> (h\u0113) + Objeto (bebida).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u559d\u6c34<\/strong> (W\u01d2 h\u0113 shu\u01d0)<br>Eu bebo \u00e1gua.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-querer-ou-precisar-de-algo-\u8981-yao\">Querer ou precisar de algo \u2013 \u8981 (y\u00e0o)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u8981<\/strong> (y\u00e0o) \u00e9 amplamente usado em chin\u00eas para expressar &#8220;querer&#8221;, &#8220;precisar&#8221; ou &#8220;estar prestes a fazer algo&#8221;. Seu significado depende do contexto e da estrutura da frase.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8981<\/strong> (y\u00e0o) \u00e9 frequentemente usado para indicar que algu\u00e9m deseja algo. A estrutura b\u00e1sica \u00e9:<br>Sujeito + <strong>\u8981<\/strong> (y\u00e0o) + Objeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u8981\u6c34 <\/strong>(W\u01d2 y\u00e0o shu\u01d0)<br>Eu quero \u00e1gua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8981<\/strong> (y\u00e0o) tamb\u00e9m pode indicar inten\u00e7\u00e3o de realizar uma a\u00e7\u00e3o. A estrutura \u00e9: Sujeito + <strong>\u8981 <\/strong>(y\u00e0o) + Verbo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u8981\u5403<\/strong> (W\u01d2 y\u00e0o ch\u012b).<br>Eu quero comer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-gostaria-ou-desejaria-algo-\u60f3-xi\u01ceng\">&#8220;Gostaria&#8221; ou &#8220;desejaria&#8221; algo \u2013 \u60f3 (xi\u01ceng)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo\/modal <strong>\u60f3<\/strong> (xi\u01ceng) \u00e9 usado para expressar desejos, vontades ou inten\u00e7\u00f5es, sendo equivalente a &#8220;gostaria de&#8221;, &#8220;desejaria&#8221; ou &#8220;quero&#8221; em portugu\u00eas. \u00c9 menos direto que <strong>\u8981<\/strong> (y\u00e0o), o que o torna mais educado ou menos urgente em contextos sociais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A estrutura b\u00e1sica para expressar desejo \u00e9: Sujeito + <strong>\u60f3<\/strong> (xi\u01ceng) + Verbo\/Objeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u60f3\u53bb\u559d\u6c34<\/strong> (W\u01d2 xi\u01ceng q\u00f9 h\u0113 shu\u01d0)<br>Eu gostaria de beber \u00e1gua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u60f3\u53bb\u65c5\u884c <\/strong>(W\u01d2 xi\u01ceng q\u00f9 l\u01dax\u00edng)<br>Eu gostaria de viajar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-estar-localizado-em-algum-lugar-\u5728-zai\">Estar localizado em algum lugar \u2013 \u5728 (z\u00e0i)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo\/preposi\u00e7\u00e3o <strong>\u5728<\/strong> (z\u00e0i) \u00e9 usado para indicar que algo ou algu\u00e9m &#8220;est\u00e1 em&#8221; um local. Em portugu\u00eas, equivale a &#8220;estar em&#8221; ou &#8220;ficar em&#8221;. <strong>\u5728<\/strong> (z\u00e0i) n\u00e3o deve ser confundido com <strong>\u662f<\/strong> (sh\u00ec), que \u00e9 usado para expressar identidade ou descri\u00e7\u00e3o, mas n\u00e3o localiza\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estrutura b\u00e1sica com <strong>\u5728<\/strong> (z\u00e0i): Sujeito + <strong>\u5728<\/strong> (z\u00e0i) + Localiza\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u5546\u5e97\u5728\u8857\u4e0a<\/strong> (Sh\u0101ngdi\u00e0n z\u00e0i ji\u0113 sh\u00e0ng)<br>A loja est\u00e1 na rua.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-dar-\u7ed9-gei\">Dar \u2013 \u7ed9 (g\u011bi)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u7ed9<\/strong> (g\u011bi) significa literalmente &#8220;dar&#8221; e \u00e9 amplamente utilizado em frases para indicar a a\u00e7\u00e3o de entregar, oferecer ou passar algo para algu\u00e9m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estrutura b\u00e1sica com <strong>\u7ed9<\/strong> (g\u011bi): Sujeito + <strong>\u7ed9<\/strong> (g\u011bi) + Objeto indireto + Objeto direto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u7ed9\u6211\u4e00\u676f\u6c34<\/strong> (G\u011bi w\u01d2 y\u012b b\u0113i shu\u01d0).<br>D\u00ea-me um copo d&#8217;\u00e1gua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No contexto de pedidos, usar <strong>\u7ed9<\/strong> (g\u011bi) com <strong>\u6211<\/strong> (w\u01d2) \u00e9 considerado educado em chin\u00eas, embora pare\u00e7a direto e um pouco rude para falantes de portugu\u00eas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u8bf7\u7ed9\u6211\u4e00\u5f20\u5730\u56fe <\/strong>(Q\u01d0ng g\u011bi w\u01d2 y\u012b zh\u0101ng d\u00ect\u00fa).<br>D\u00ea-me um mapa, por favor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-respostas-sim-e-nao-em-mandarim\">Respostas &#8220;sim&#8221; e &#8220;n\u00e3o&#8221; em mandarim<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Em mandarim, as respostas a perguntas de sim\/n\u00e3o geralmente dependem do verbo ou da estrutura usada na pergunta. N\u00e3o h\u00e1 uma \u00fanica forma de responder com &#8220;sim&#8221; e &#8220;n\u00e3o&#8221; em chin\u00eas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O que voc\u00ea precisa fazer \u00e9 ouvir a pergunta que est\u00e1 sendo feita \u2013 se ouvir um <strong>\u5417<\/strong> (ma) ao final, saber\u00e1 que ela requer uma resposta sim\/n\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estrutura b\u00e1sica para responder: Na forma afirmativa, voc\u00ea deve repitir o verbo ou o termo principal da pergunta. Na forma negativa, usar a part\u00edcula de nega\u00e7\u00e3o <strong>\u4e0d<\/strong> (b\u00f9) ou <strong>\u6ca1<\/strong> (m\u00e9i) antes do verbo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pergunta com o verbo <strong>\u8981<\/strong> (y\u00e0o):<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u8981\u6c34\u5417\uff1f<\/strong>(N\u01d0 y\u00e0o shu\u01d0 ma?)<br>Voc\u00ea quer \u00e1gua?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Resposta afirmativa: <strong>\u8981<\/strong> (y\u00e0o) = Quero.<\/li>\n\n\n\n<li>Resposta negativa: <strong>\u4e0d\u8981<\/strong> (b\u00f9 y\u00e0o) = N\u00e3o quero.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Pergunta com o verbo \u662f (sh\u00ec):<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u662f\u8001\u5e08\u5417\uff1f<\/strong>(N\u01d0 sh\u00ec l\u01ceosh\u012b ma?)<br>Voc\u00ea \u00e9 professor?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Resposta afirmativa: <strong>\u662f<\/strong> (sh\u00ec) = Sou.<\/li>\n\n\n\n<li>Resposta negativa: <strong>\u4e0d\u662f<\/strong> (b\u00fa sh\u00ec) = N\u00e3o sou.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Pergunta com o verbo \u6709 (y\u01d2u):<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u6709\u72d7\u5417\uff1f<\/strong>(N\u01d0 y\u01d2u g\u01d2u ma?)<br>Voc\u00ea tem um cachorro?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Resposta afirmativa: <strong>\u6709<\/strong> (y\u01d2u) = Tenho.<\/li>\n\n\n\n<li>Resposta negativa: <strong>\u6ca1\u6709<\/strong> (m\u00e9i y\u01d2u) = N\u00e3o tenho.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Agora que voc\u00ea est\u00e1 familiarizado com os principais verbos e frases em chin\u00eas, est\u00e1 pronto para come\u00e7ar a praticar a pron\u00fancia e compreender aspectos importantes do idioma. Vamos abordar alguns aspectos que os estudantes de chin\u00eas devem compreender sobre o idioma.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-nocoes-basicas-do-chines\">No\u00e7\u00f5es b\u00e1sicas do chin\u00eas<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-tons\">Tons<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O mandarim, uma das v\u00e1rias l\u00ednguas chinesas, tem um n\u00famero limitado de s\u00edlabas. Por isso, os tons s\u00e3o fundamentais para diferenciar palavras que t\u00eam a mesma pron\u00fancia b\u00e1sica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 quatro tons em mandarim, al\u00e9m de um tom neutro:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O primeiro tom (-) \u00e9 constante, alto e nivelado.<\/li>\n\n\n\n<li>O segundo tom (\u2018) ascendente, sobe para o agudo.<\/li>\n\n\n\n<li>O terceiro tom (v) descendente e depois ascendente, desce para o grave e depois sobe.<\/li>\n\n\n\n<li>O quarto tom (`) desce para o grave.<\/li>\n\n\n\n<li>O quinto tom \u00e9 neutro e exige uma \u00fanica e abrupta articula\u00e7\u00e3o.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Quando aprender novas palavras em chin\u00eas, memorize n\u00e3o s\u00f3 os sons, mas tamb\u00e9m os tons. Embora pare\u00e7a dif\u00edcil no in\u00edcio, pratique constantemente e tente imitar a pron\u00fancia de falantes nativos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-pinyin\">Pinyin<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para escrever o mandarim, o sistema oficial chamado <em>pinyin <\/em>\u00e9 amplamente utilizado. Ele transcreve os sons do mandarim usando o alfabeto latino e adiciona marcas de tom acima das vogais para indicar o tom correto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, uma das palavras mais conhecidas em chin\u00eas \u00e9 <strong>\u4f60\u597d<\/strong> (n\u01d0 h\u01ceo), que significa &#8216;ol\u00e1&#8217;. Literalmente, &#8216;n\u01d0&#8217; \u00e9 &#8216;voc\u00ea&#8217; e &#8216;h\u01ceo&#8217; \u00e9 &#8216;bom&#8217; (&#8220;voc\u00ea bom&#8221;).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em <strong>\u4f60\u597d <\/strong>(n\u01d0 h\u01ceo), que significa &#8220;ol\u00e1&#8221;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A marca na vogal \u01d0 (\u02c7) indica o terceiro tom (descendente-ascendente).<\/li>\n\n\n\n<li>A marca na vogal \u01ceo (\u02c7) tamb\u00e9m \u00e9 do terceiro tom.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Em <em>pinyin<\/em>, as marcas acima das vogais em cada palavra indicam os tons utilizados. Se a marca \u00e9 neutra (por exemplo, \u0101), isso indica o primeiro tom. Se a marca \u00e9 ascendente (\u00e1), \u00e9 o segundo tom. Se a marca cai e sobe (\u01ce), isso \u00e9 o terceiro tom. Se a marca for descendente (\u00e0), \u00e9 o quarto tom. Se n\u00e3o houver marca, isso significa que o tom \u00e9 neutro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o tenha medo de errar: \u00e9 melhor tentar e ajustar sua pron\u00fancia com o tempo do que n\u00e3o praticar!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-escrever-em-chines\">Como escrever em chin\u00eas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 verdade que o chin\u00eas tem muitos caracteres que precisam ser aprendidos individualmente. S\u00e3o necess\u00e1rios cerca de 2.500 caracteres para atingir o n\u00edvel de um aluno da escola prim\u00e1ria! As palavras em chin\u00eas podem ser formadas por um ou mais caracteres. Cada caractere tem seu pr\u00f3prio significado e pode ser uma palavra completa ou parte de uma palavra composta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esses caracteres n\u00e3o t\u00eam uma correspond\u00eancia direta com a pron\u00fancia das palavras em outros idiomas, mas eles s\u00e3o representados no sistema de pinyin, que usa o alfabeto latino para indicar a fon\u00e9tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada caractere \u00e9 composto por blocos chamados radicais. Esses radicais podem indicar o campo sem\u00e2ntico do caractere, embora nem todos os radicais tenham significado por si s\u00f3. Por exemplo, o radical de &#8220;telhado&#8221; (<strong>\u5b80<\/strong>) pode ser combinado com outros radicais para formar palavras. Se combinado com o radical de &#8220;porco&#8221; (<strong>\u8c55<\/strong>), forma o caractere <strong>\u5bb6<\/strong> (ji\u0101), que significa &#8220;casa&#8221;, e se combinado com o radical de &#8220;jade&#8221; (<strong>\u7389<\/strong>), forma <strong>\u5b9d<\/strong> (b\u01ceo), que significa &#8220;tesouro&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 medida que voc\u00ea progride no aprendizado do chin\u00eas, come\u00e7ar\u00e1 a reconhecer os radicais em cada caractere. Com o tempo, voc\u00ea notar\u00e1 padr\u00f5es que facilitar\u00e3o a memoriza\u00e7\u00e3o de novos caracteres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De fato, assim como os alunos das escolas dos pa\u00edses de l\u00edngua portuguesa s\u00e3o submetidos a testes de ortografia com mais de 2.000 palavras, o processo de memoriza\u00e7\u00e3o dos caracteres no mandarim segue uma l\u00f3gica semelhante.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-formacao-de-palavras-em-chines\">Forma\u00e7\u00e3o de palavras em chin\u00eas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como voc\u00ea pode ver, as palavras em chin\u00eas s\u00e3o formadas pela combina\u00e7\u00e3o de radicais. Esses caracteres s\u00e3o ent\u00e3o combinados para formar palavras. Por exemplo, a palavra para &#8220;computador&#8221; <strong>\u7535\u8111 <\/strong>(di\u00e0n n\u01ceo) combina &#8220;el\u00e9trico&#8221; (<strong>\u7535<\/strong> \/ di\u00e0n) com &#8220;c\u00e9rebro&#8221; (<strong>\u8111<\/strong> \/ n\u01ceo), dando o significado de &#8220;c\u00e9rebro el\u00e9trico&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 milhares dessas combina\u00e7\u00f5es em chin\u00eas. Um dos exemplos mais famosos de uma combina\u00e7\u00e3o pouco clara \u00e9 <strong>\u4e1c\u897f<\/strong> (d\u014dng x\u012b). A tradu\u00e7\u00e3o literal de <strong>\u4e1c\u897f<\/strong> \u00e9 &#8220;leste oeste&#8221;, mas seu significado real \u00e9 &#8220;coisa&#8221; ou &#8220;objeto&#8221;. Embora o motivo dessa combina\u00e7\u00e3o n\u00e3o seja claro, <strong>\u4e1c\u897f <\/strong>\u00e9 uma das palavras mais \u00fateis e frequentemente usadas em mandarim para se referir a algo de forma geral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em vez de ver isso como algo complicado, pense na criatividade espantosa que foi necess\u00e1ria para criar todas essas palavras. Isso mostra como o idioma chin\u00eas \u00e9, na verdade, incrivelmente expressivo e criativo!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es finais<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aprender vai al\u00e9m da simples memoriza\u00e7\u00e3o. H\u00e1 muitas nuances e significados por tr\u00e1s de muitas palavras em mandarim que n\u00e3o podem ser totalmente abordados neste artigo. Al\u00e9m disso, n\u00e3o abordamos a ordem das palavras, que difere significativamente entre o chin\u00eas e o portugu\u00eas. N\u00e3o desanime! Com pr\u00e1tica constante e a orienta\u00e7\u00e3o certa, voc\u00ea ver\u00e1 progressos r\u00e1pidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O segredo est\u00e1 em praticar regularmente a fala, a leitura e a escrita em chin\u00eas. Isso s\u00f3 pode ser realmente alcan\u00e7ado atrav\u00e9s de conversas com falantes fluentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aulas de chin\u00eas online podem ser muito mais eficazes do que estudar sozinho. Nossos professores podem ajud\u00e1-lo a acertar os tons e a usar as palavras no contexto correto, acelerando seu progresso. <a href=\"https:\/\/app.hridiomas.com\/teachers\/languages\/Chinese\">N\u00e3o deixe de conferir nossos professores de chin\u00eas online<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enquanto isso, <strong>\u795d\u4f60\u597d\u8fd0! <\/strong>(zh\u00f9 n\u01d0 h\u01ceo y\u00f9n!) \u2013 Boa sorte para voc\u00ea!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Original de <a href=\"https:\/\/preply.com\/pt\/blog\/palavras-basicas-em-chines\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Preply<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acredite! Aprender o b\u00e1sico de chin\u00eas mandarim pode ser um desafio, mas n\u00e3o \u00e9 imposs\u00edvel. Algumas palavras b\u00e1sicas ajudar\u00e3o voc\u00ea a deixar de ser um completo iniciante e conseguir at\u00e9 manter conversas. Se voc\u00ea est\u00e1 planejando uma viagem \u00e0 China, procurando expandir seus horizontes culturais ou simplesmente desejando se desafiar com um novo idioma, aprender<\/p>\n","protected":false},"author":1,"featured_media":83,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-74","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender &#8226; Aprender Mandarim<\/title>\n<meta name=\"description\" content=\"Falar o b\u00e1sico de mandarim n\u00e3o \u00e9 t\u00e3o f\u00e1cil assim. Mas estas palavras ajudar\u00e3o voc\u00ea a deixar de ser um completo iniciante e manter conversas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender &#8226; Aprender Mandarim\" \/>\n<meta property=\"og:description\" content=\"Falar o b\u00e1sico de mandarim n\u00e3o \u00e9 t\u00e3o f\u00e1cil assim. Mas estas palavras ajudar\u00e3o voc\u00ea a deixar de ser um completo iniciante e manter conversas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/\" \/>\n<meta property=\"og:site_name\" content=\"Aprender Mandarim\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hridiomas\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-10T15:50:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T15:21:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2024\/07\/destaque-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hridiomas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hridiomas\" \/>\n<meta name=\"twitter:site\" content=\"@hridiomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hridiomas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/\"},\"author\":{\"name\":\"hridiomas\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/person\\\/074f113560c2f5d2d8531b6fb060d851\"},\"headline\":\"Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender\",\"datePublished\":\"2024-07-10T15:50:20+00:00\",\"dateModified\":\"2025-03-24T15:21:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/\"},\"wordCount\":3669,\"publisher\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/07\\\/destaque-1.jpg\",\"articleSection\":[\"Dicas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/\",\"name\":\"Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender &#8226; Aprender Mandarim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/07\\\/destaque-1.jpg\",\"datePublished\":\"2024-07-10T15:50:20+00:00\",\"dateModified\":\"2025-03-24T15:21:26+00:00\",\"description\":\"Falar o b\u00e1sico de mandarim n\u00e3o \u00e9 t\u00e3o f\u00e1cil assim. Mas estas palavras ajudar\u00e3o voc\u00ea a deixar de ser um completo iniciante e manter conversas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/07\\\/destaque-1.jpg\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/07\\\/destaque-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#website\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/\",\"name\":\"Aprender Mandarim\",\"description\":\"Dicas para aprender chin\u00eas\",\"publisher\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#organization\",\"name\":\"HR idiomas\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-hricon.png\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-hricon.png\",\"width\":512,\"height\":512,\"caption\":\"HR idiomas\"},\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hridiomas\",\"https:\\\/\\\/x.com\\\/hridiomas\",\"https:\\\/\\\/www.instagram.com\\\/hridiomas\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2678452\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/HridiomasBr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/person\\\/074f113560c2f5d2d8531b6fb060d851\",\"name\":\"hridiomas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/litespeed\\\/avatar\\\/14\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/litespeed\\\/avatar\\\/14\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/litespeed\\\/avatar\\\/14\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380\",\"caption\":\"hridiomas\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender &#8226; Aprender Mandarim","description":"Falar o b\u00e1sico de mandarim n\u00e3o \u00e9 t\u00e3o f\u00e1cil assim. Mas estas palavras ajudar\u00e3o voc\u00ea a deixar de ser um completo iniciante e manter conversas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/","og_locale":"pt_BR","og_type":"article","og_title":"Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender &#8226; Aprender Mandarim","og_description":"Falar o b\u00e1sico de mandarim n\u00e3o \u00e9 t\u00e3o f\u00e1cil assim. Mas estas palavras ajudar\u00e3o voc\u00ea a deixar de ser um completo iniciante e manter conversas.","og_url":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/","og_site_name":"Aprender Mandarim","article_publisher":"https:\/\/www.facebook.com\/hridiomas","article_published_time":"2024-07-10T15:50:20+00:00","article_modified_time":"2025-03-24T15:21:26+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2024\/07\/destaque-1.jpg","type":"image\/jpeg"}],"author":"hridiomas","twitter_card":"summary_large_image","twitter_creator":"@hridiomas","twitter_site":"@hridiomas","twitter_misc":{"Escrito por":"hridiomas","Est. tempo de leitura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/#article","isPartOf":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/"},"author":{"name":"hridiomas","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/person\/074f113560c2f5d2d8531b6fb060d851"},"headline":"Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender","datePublished":"2024-07-10T15:50:20+00:00","dateModified":"2025-03-24T15:21:26+00:00","mainEntityOfPage":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/"},"wordCount":3669,"publisher":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#organization"},"image":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/#primaryimage"},"thumbnailUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2024\/07\/destaque-1.jpg","articleSection":["Dicas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/","url":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/","name":"Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender &#8226; Aprender Mandarim","isPartOf":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/#primaryimage"},"image":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/#primaryimage"},"thumbnailUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2024\/07\/destaque-1.jpg","datePublished":"2024-07-10T15:50:20+00:00","dateModified":"2025-03-24T15:21:26+00:00","description":"Falar o b\u00e1sico de mandarim n\u00e3o \u00e9 t\u00e3o f\u00e1cil assim. Mas estas palavras ajudar\u00e3o voc\u00ea a deixar de ser um completo iniciante e manter conversas.","breadcrumb":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/#primaryimage","url":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2024\/07\/destaque-1.jpg","contentUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2024\/07\/destaque-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/palavras-e-frases-basicas-em-chines-que-todo-iniciante-deve-aprender\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/hridiomas.com\/aprender-mandarim\/"},{"@type":"ListItem","position":2,"name":"Palavras e frases b\u00e1sicas em chin\u00eas que todo iniciante deve aprender"}]},{"@type":"WebSite","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#website","url":"https:\/\/hridiomas.com\/aprender-mandarim\/","name":"Aprender Mandarim","description":"Dicas para aprender chin\u00eas","publisher":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hridiomas.com\/aprender-mandarim\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#organization","name":"HR idiomas","url":"https:\/\/hridiomas.com\/aprender-mandarim\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/logo\/image\/","url":"https:\/\/hridiomas.com\/wp-content\/uploads\/2021\/04\/cropped-hricon.png","contentUrl":"https:\/\/hridiomas.com\/wp-content\/uploads\/2021\/04\/cropped-hricon.png","width":512,"height":512,"caption":"HR idiomas"},"image":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hridiomas","https:\/\/x.com\/hridiomas","https:\/\/www.instagram.com\/hridiomas","https:\/\/www.linkedin.com\/company\/2678452","https:\/\/www.youtube.com\/c\/HridiomasBr"]},{"@type":"Person","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/person\/074f113560c2f5d2d8531b6fb060d851","name":"hridiomas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/litespeed\/avatar\/14\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380","url":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/litespeed\/avatar\/14\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380","contentUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/litespeed\/avatar\/14\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380","caption":"hridiomas"}}]}},"_links":{"self":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/posts\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":0,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/posts\/74\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/media\/83"}],"wp:attachment":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/media?parent=74"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/categories?post=74"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/tags?post=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}