{"id":277,"date":"2025-01-28T09:10:50","date_gmt":"2025-01-28T12:10:50","guid":{"rendered":"https:\/\/hridiomas.com\/aprender-mandarim\/?p=277"},"modified":"2025-03-24T12:47:39","modified_gmt":"2025-03-24T15:47:39","slug":"uso-do-verbo-qu-ir-em-mandarim","status":"publish","type":"post","link":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/","title":{"rendered":"Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O verbo <strong>\u53bb<\/strong> (q\u00f9), que significa &#8220;ir&#8221;, \u00e9 amplamente usado em mandarim para expressar movimento em dire\u00e7\u00e3o a um lugar ou para realizar uma a\u00e7\u00e3o. Abaixo est\u00e3o os usos e constru\u00e7\u00f5es mais comuns desse verbo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-indicar-movimento-para-um-lugar\">Indicar movimento para um lugar<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u53bb<\/strong> (q\u00f9) \u00e9 usado para indicar que algu\u00e9m est\u00e1 indo para um lugar. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estrutura: Sujeito + <strong>\u53bb<\/strong> + Lugar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u53bb\u5b66\u6821\u3002<\/strong>(W\u01d2 q\u00f9 xu\u00e9xi\u00e0o)<br>Eu vou \u00e0 escola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u53bb\u5546\u5e97\u3002<\/strong>(T\u0101 q\u00f9 sh\u0101ngdi\u00e0n)<br>Ele vai \u00e0 loja.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ir-para-fazer-algo\">Ir para fazer algo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quando usado com outro verbo, <strong>\u53bb<\/strong> (q\u00f9) pode indicar que algu\u00e9m est\u00e1 indo para realizar uma a\u00e7\u00e3o espec\u00edfica, indica que a pessoa est\u00e1 se deslocando para outro lugar para realizar a a\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estrutura: Sujeito + \u53bb + Verbo + Objeto<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u53bb\u4e70\u4e1c\u897f\u3002<\/strong>(W\u01d2 q\u00f9 m\u01cei d\u014dngx\u012b)<br>Eu vou comprar coisas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u4eec\u53bb\u5403\u996d\u3002<\/strong>(T\u0101men q\u00f9 ch\u012bf\u00e0n)<br>Eles v\u00e3o comer.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-indicar-um-tempo-futuro\">Indicar um tempo futuro<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u53bb<\/strong> tamb\u00e9m pode ser usado em frases para sugerir inten\u00e7\u00f5es ou a\u00e7\u00f5es futuras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u660e\u5929\u6211\u53bb\u5317\u4eac\u3002<\/strong>(M\u00edngti\u0101n w\u01d2 q\u00f9 B\u011bij\u012bng)<br>Amanh\u00e3, eu vou a Pequim.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u4eec\u4e0b\u4e2a\u6708\u53bb\u65c5\u884c\u3002<\/strong>(W\u01d2men xi\u00e0 g\u00e8 yu\u00e8 q\u00f9 l\u01dax\u00edng)<br>No pr\u00f3ximo m\u00eas, n\u00f3s vamos viajar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-combinacao-com-outros-adverbios-ou-verbos\">Combina\u00e7\u00e3o com outros adv\u00e9rbios ou verbos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u53bb<\/strong> pode ser combinado com palavras como <strong>\u8981<\/strong> (y\u00e0o, querer\/planejar) para expressar uma inten\u00e7\u00e3o de ir a algum lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u8981\u53bb\u770b\u7535\u5f71\u3002<\/strong>(W\u01d2 y\u00e0o q\u00f9 k\u00e0n di\u00e0ny\u01d0ng)<br>Eu quero ir assistir a um filme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u60f3\u53bb\u5b66\u4e60\u4e2d\u6587\u3002<\/strong>(T\u0101 xi\u01ceng q\u00f9 xu\u00e9x\u00ed zh\u014dngw\u00e9n)<br>Ele gostaria de ir estudar chin\u00eas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-forma-negativa-com-\u4e0d-bu\">Forma negativa com \u4e0d (b\u00f9)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para negar o verbo <strong>\u53bb<\/strong> (q\u00f9), usa-se <strong>\u4e0d\u53bb<\/strong> (b\u00fa q\u00f9), que significa &#8220;n\u00e3o ir&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u4e0d\u53bb\u516c\u56ed\u3002<\/strong>(W\u01d2 b\u00fa q\u00f9 g\u014dngyu\u00e1n)<br>Eu n\u00e3o vou ao parque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u4eec\u4eca\u5929\u4e0d\u53bb\u4e0a\u8bfe\u3002<\/strong>(T\u0101men j\u012bnti\u0101n b\u00fa q\u00f9 sh\u00e0ngk\u00e8)<br>Eles n\u00e3o v\u00e3o \u00e0 aula hoje.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-perguntas-com-\u53bb\">Perguntas com \u53bb<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para fazer perguntas com <strong>\u53bb<\/strong>, pode-se usar a part\u00edcula <strong>\u5417<\/strong> (ma) no final ou a estrutura alternativa de repeti\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u53bb\u4e2d\u56fd\u5417\uff1f<\/strong>(N\u01d0 q\u00f9 Zh\u014dnggu\u00f3 ma?)<br>Voc\u00ea vai \u00e0 China?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u4eec\u53bb\u5403\u996d\u5417\uff1f<\/strong>(T\u0101men q\u00f9 ch\u012bf\u00e0n ma?)<br>Eles v\u00e3o comer?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exemplos com repeti\u00e7\u00e3o:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u53bb\u4e0d\u53bb\u5317\u4eac\uff1f<\/strong>(N\u01d0 q\u00f9 b\u00fa q\u00f9 B\u011bij\u012bng?)<br>Voc\u00ea vai ou n\u00e3o vai a Pequim?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-expressoes-comuns-com-\u53bb\">Express\u00f5es comuns com \u53bb<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u53bb <\/strong>\u00e9 amplamente utilizado em muitas frases e express\u00f5es do dia a dia:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u53bb\u54ea\u91cc\uff1f<\/strong>(Q\u00f9 n\u01cel\u01d0?) \u2013 Para onde voc\u00ea vai?<\/li>\n\n\n\n<li><strong>\u53bb\u65c5\u6e38<\/strong> (q\u00f9 l\u01day\u00f3u) \u2013 Ir viajar.<\/li>\n\n\n\n<li><strong>\u53bb\u5de5\u4f5c<\/strong> (q\u00f9 g\u014dngzu\u00f2) \u2013 Ir trabalhar.<\/li>\n\n\n\n<li><strong>\u53bb\u770b\u533b\u751f<\/strong> (q\u00f9 k\u00e0n y\u012bsh\u0113ng) \u2013 Ir ao m\u00e9dico.<\/li>\n\n\n\n<li><strong>\u53bb\u4e16<\/strong> (q\u00f9sh\u00ec) \u2013 Faleceu (eufemismo para morte).<\/li>\n\n\n\n<li><strong>\u8bf4\u53bb\u5c31\u53bb<\/strong> (shu\u014d q\u00f9 ji\u00f9 q\u00f9) \u2013 Decidir e ir imediatamente.<\/li>\n\n\n\n<li><strong>\u8d70\u6765\u8d70\u53bb<\/strong> (z\u01d2u l\u00e1i z\u01d2u q\u00f9) \u2013 Andar de um lado para o outro.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-diferencas-entre-\u53bb-qu-e-\u6765-lai\">Diferen\u00e7as entre \u53bb (q\u00f9) e \u6765 (l\u00e1i)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os verbos <strong>\u53bb<\/strong> (q\u00f9) e <strong>\u6765<\/strong> (l\u00e1i) em mandarim s\u00e3o usados para descrever movimento ou dire\u00e7\u00e3o, mas t\u00eam diferen\u00e7as importantes que precisam ser entendidas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u53bb-qu-ir\">\u53bb (q\u00f9): Ir<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u53bb<\/strong> \u00e9 usado para descrever movimento para longe do falante ou do local onde ele est\u00e1 no momento. Ele indica que a a\u00e7\u00e3o est\u00e1 se afastando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u53bb\u56fe\u4e66\u9986\u4e86\u3002<\/strong>(T\u0101 q\u00f9 t\u00fash\u016bgu\u01cen le)<br>Ele foi para a biblioteca. (O movimento ocorre para um local distante do falante).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u660e\u5929\u6211\u8981\u53bb\u4e0a\u6d77\u3002<\/strong>(M\u00edngti\u0101n w\u01d2 y\u00e0o q\u00f9 Sh\u00e0ngh\u01cei)<br>Amanh\u00e3 eu vou para Xangai. (O falante est\u00e1 indo para outro lugar).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u6765-lai-vir\">\u6765 (l\u00e1i): Vir<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u6765<\/strong>, por outro lado, \u00e9 usado para descrever movimento em dire\u00e7\u00e3o ao falante ou ao local onde ele est\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u6765\u6211\u5bb6\u4e86\u3002<\/strong>(T\u0101 l\u00e1i w\u01d2 ji\u0101 le)<br>Ele veio para minha casa. (O movimento ocorre na dire\u00e7\u00e3o do falante).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u660e\u5929\u6211\u670b\u53cb\u8981\u6765\u4e0a\u6d77\u3002<\/strong>(M\u00edngti\u0101n w\u01d2 p\u00e9ngy\u01d2u y\u00e0o l\u00e1i Sh\u00e0ngh\u01cei)<br>Amanh\u00e3 meu amigo vir\u00e1 para Xangai. (O movimento ocorre na dire\u00e7\u00e3o do local onde o falante est\u00e1 ou estar\u00e1).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma maneira simples de lembrar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u53bb<\/strong> (q\u00f9) = Para longe do falante.<\/li>\n\n\n\n<li><strong>\u6765 <\/strong>(l\u00e1i) = Na dire\u00e7\u00e3o do falante.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Como voc\u00ea viu, o verbo <strong>\u53bb<\/strong> (q\u00f9) \u00e9 essencial no mandarim, usado em muitos contextos do dia a dia. Com pr\u00e1tica, voc\u00ea logo se sentir\u00e1 confiante em aplic\u00e1-lo corretamente!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O verbo \u53bb (q\u00f9), que significa &#8220;ir&#8221;, \u00e9 amplamente usado em mandarim para expressar movimento em dire\u00e7\u00e3o a um lugar ou para realizar uma a\u00e7\u00e3o. Abaixo est\u00e3o os usos e constru\u00e7\u00f5es mais comuns desse verbo. Indicar movimento para um lugar O verbo \u53bb (q\u00f9) \u00e9 usado para indicar que algu\u00e9m est\u00e1 indo para um lugar.<\/p>\n","protected":false},"author":1,"featured_media":282,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[8],"class_list":["post-277","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gramatica","tag-verbos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim &#8226; Aprender Mandarim<\/title>\n<meta name=\"description\" content=\"O verbo \u53bb (q\u00f9), que significa &quot;ir&quot;, \u00e9 amplamente usado em mandarim para expressar movimento em dire\u00e7\u00e3o a um lugar ou para realizar uma a\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim &#8226; Aprender Mandarim\" \/>\n<meta property=\"og:description\" content=\"O verbo \u53bb (q\u00f9), que significa &quot;ir&quot;, \u00e9 amplamente usado em mandarim para expressar movimento em dire\u00e7\u00e3o a um lugar ou para realizar uma a\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/\" \/>\n<meta property=\"og:site_name\" content=\"Aprender Mandarim\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hridiomas\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T12:10:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T15:47:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hridiomas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hridiomas\" \/>\n<meta name=\"twitter:site\" content=\"@hridiomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hridiomas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/\"},\"author\":{\"name\":\"hridiomas\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/person\\\/074f113560c2f5d2d8531b6fb060d851\"},\"headline\":\"Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim\",\"datePublished\":\"2025-01-28T12:10:50+00:00\",\"dateModified\":\"2025-03-24T15:47:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/\"},\"wordCount\":661,\"publisher\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2025\\\/01\\\/destaque-3.jpg\",\"keywords\":[\"verbos\"],\"articleSection\":[\"Gram\u00e1tica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/\",\"name\":\"Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim &#8226; Aprender Mandarim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2025\\\/01\\\/destaque-3.jpg\",\"datePublished\":\"2025-01-28T12:10:50+00:00\",\"dateModified\":\"2025-03-24T15:47:39+00:00\",\"description\":\"O verbo \u53bb (q\u00f9), que significa \\\"ir\\\", \u00e9 amplamente usado em mandarim para expressar movimento em dire\u00e7\u00e3o a um lugar ou para realizar uma a\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2025\\\/01\\\/destaque-3.jpg\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2025\\\/01\\\/destaque-3.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-qu-ir-em-mandarim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#website\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/\",\"name\":\"Aprender Mandarim\",\"description\":\"Dicas para aprender chin\u00eas\",\"publisher\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#organization\",\"name\":\"HR idiomas\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-hricon.png\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-hricon.png\",\"width\":512,\"height\":512,\"caption\":\"HR idiomas\"},\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hridiomas\",\"https:\\\/\\\/x.com\\\/hridiomas\",\"https:\\\/\\\/www.instagram.com\\\/hridiomas\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2678452\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/HridiomasBr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/person\\\/074f113560c2f5d2d8531b6fb060d851\",\"name\":\"hridiomas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/litespeed\\\/avatar\\\/14\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/litespeed\\\/avatar\\\/14\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/litespeed\\\/avatar\\\/14\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380\",\"caption\":\"hridiomas\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim &#8226; Aprender Mandarim","description":"O verbo \u53bb (q\u00f9), que significa \"ir\", \u00e9 amplamente usado em mandarim para expressar movimento em dire\u00e7\u00e3o a um lugar ou para realizar uma a\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/","og_locale":"pt_BR","og_type":"article","og_title":"Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim &#8226; Aprender Mandarim","og_description":"O verbo \u53bb (q\u00f9), que significa \"ir\", \u00e9 amplamente usado em mandarim para expressar movimento em dire\u00e7\u00e3o a um lugar ou para realizar uma a\u00e7\u00e3o.","og_url":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/","og_site_name":"Aprender Mandarim","article_publisher":"https:\/\/www.facebook.com\/hridiomas","article_published_time":"2025-01-28T12:10:50+00:00","article_modified_time":"2025-03-24T15:47:39+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-3.jpg","type":"image\/jpeg"}],"author":"hridiomas","twitter_card":"summary_large_image","twitter_creator":"@hridiomas","twitter_site":"@hridiomas","twitter_misc":{"Escrito por":"hridiomas","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/#article","isPartOf":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/"},"author":{"name":"hridiomas","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/person\/074f113560c2f5d2d8531b6fb060d851"},"headline":"Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim","datePublished":"2025-01-28T12:10:50+00:00","dateModified":"2025-03-24T15:47:39+00:00","mainEntityOfPage":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/"},"wordCount":661,"publisher":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#organization"},"image":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/#primaryimage"},"thumbnailUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-3.jpg","keywords":["verbos"],"articleSection":["Gram\u00e1tica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/","url":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/","name":"Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim &#8226; Aprender Mandarim","isPartOf":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/#primaryimage"},"image":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/#primaryimage"},"thumbnailUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-3.jpg","datePublished":"2025-01-28T12:10:50+00:00","dateModified":"2025-03-24T15:47:39+00:00","description":"O verbo \u53bb (q\u00f9), que significa \"ir\", \u00e9 amplamente usado em mandarim para expressar movimento em dire\u00e7\u00e3o a um lugar ou para realizar uma a\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/#primaryimage","url":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-3.jpg","contentUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-3.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-qu-ir-em-mandarim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/hridiomas.com\/aprender-mandarim\/"},{"@type":"ListItem","position":2,"name":"Uso do verbo \u53bb (q\u00f9) \u201cir\u201d em mandarim"}]},{"@type":"WebSite","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#website","url":"https:\/\/hridiomas.com\/aprender-mandarim\/","name":"Aprender Mandarim","description":"Dicas para aprender chin\u00eas","publisher":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hridiomas.com\/aprender-mandarim\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#organization","name":"HR idiomas","url":"https:\/\/hridiomas.com\/aprender-mandarim\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/logo\/image\/","url":"https:\/\/hridiomas.com\/wp-content\/uploads\/2021\/04\/cropped-hricon.png","contentUrl":"https:\/\/hridiomas.com\/wp-content\/uploads\/2021\/04\/cropped-hricon.png","width":512,"height":512,"caption":"HR idiomas"},"image":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hridiomas","https:\/\/x.com\/hridiomas","https:\/\/www.instagram.com\/hridiomas","https:\/\/www.linkedin.com\/company\/2678452","https:\/\/www.youtube.com\/c\/HridiomasBr"]},{"@type":"Person","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/person\/074f113560c2f5d2d8531b6fb060d851","name":"hridiomas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/litespeed\/avatar\/14\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380","url":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/litespeed\/avatar\/14\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380","contentUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/litespeed\/avatar\/14\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380","caption":"hridiomas"}}]}},"_links":{"self":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/posts\/277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/comments?post=277"}],"version-history":[{"count":0,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/posts\/277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/media?parent=277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/categories?post=277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/tags?post=277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}