{"id":253,"date":"2025-01-15T16:09:14","date_gmt":"2025-01-15T19:09:14","guid":{"rendered":"https:\/\/hridiomas.com\/aprender-mandarim\/?p=253"},"modified":"2025-03-24T12:39:18","modified_gmt":"2025-03-24T15:39:18","slug":"uso-do-verbo-shi-ser-estar-em-mandarim","status":"publish","type":"post","link":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/","title":{"rendered":"Uso do verbo \u662f (sh\u00ec) &#8220;ser\/estar&#8221; em mandarim"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O verbo \u662f (sh\u00ec) \u00e9 equivalente a &#8220;ser\/estar&#8221; em portugu\u00eas, mas \u00e9 usado exclusivamente para indicar identidade, origem ou equival\u00eancias diretas. Ele n\u00e3o \u00e9 usado para expressar estados tempor\u00e1rios, como &#8220;estar feliz&#8221; ou &#8220;estar cansado&#8221; (esses casos usam outros verbos ou estruturas).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u662f\u7f8e\u56fd\u4eba <\/strong>(W\u01d2 sh\u00ec m\u011bigu\u00f3 r\u00e9n)<br>Eu sou americano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u662f\u5df4\u897f\u4eba<\/strong> (W\u01d2 sh\u00ec B\u0101x\u012b r\u00e9n)<br>Eu sou brasileiro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-estrutura-da-frase-com-\u662f-shi\">Estrutura da frase com \u662f (sh\u00ec)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A estrutura b\u00e1sica de uma frase afirmativa com <strong>\u662f<\/strong> (sh\u00ec) \u00e9: sujeito + <strong>\u662f<\/strong> (sh\u00ec) + complemento nominal (substantivo, profiss\u00e3o, nacionalidade, etc.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u662f\u8001\u5e08<\/strong> (T\u0101 sh\u00ec l\u01ceosh\u012b)<br>Ele \u00e9 professor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u4eec\u662f\u5b66\u751f<\/strong> (W\u01d2men sh\u00ec xu\u00e9sh\u0113ng)<br>N\u00f3s somos estudantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u4eec\u662f\u5b66\u751f<\/strong> (T\u0101men sh\u00ec xu\u00e9sh\u0113ng)<br>Eles s\u00e3o estudantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u5979\u662f\u533b\u751f<\/strong> (T\u0101 sh\u00ec y\u012bsh\u0113ng)<br>Ela \u00e9 m\u00e9dica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u4eec\u662f\u670b\u53cb<\/strong> (W\u01d2men sh\u00ec p\u00e9ngy\u01d2u)<br>N\u00f3s somos amigos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-uso-de-\u662f-shi-com-pronomes-e-nomes-proprios\">Uso de \u662f (sh\u00ec) com pronomes e nomes pr\u00f3prios<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O verbo <strong>\u662f<\/strong> (sh\u00ec) \u00e9 usado para conectar o sujeito ao predicado, especialmente ao identificar ou categorizar algo\/algu\u00e9m. Isso inclui pronomes pessoais e nomes pr\u00f3prios:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u662f\u674e\u534e <\/strong>(T\u0101 sh\u00ec L\u01d0 Hu\u00e1)<br>Ele \u00e9 Li Hua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u662f\u738b\u660e<\/strong> (W\u01d2 sh\u00ec W\u00e1ng M\u00edng)<br>Eu sou Wang Ming.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-forma-negativa-de-\u662f-shi\">Forma negativa de \u662f (sh\u00ec)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para negar uma frase com <strong>\u662f<\/strong> (sh\u00ec), adicione o <strong>\u4e0d<\/strong> (b\u00f9) antes de <strong>\u662f<\/strong> (sh\u00ec).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u4e0d\u662f\u4e2d\u56fd\u4eba<\/strong> (W\u01d2 b\u00f9 sh\u00ec Zh\u014dnggu\u00f3 r\u00e9n)<br>Eu n\u00e3o sou chin\u00eas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u4e0d\u662f\u8001\u5e08<\/strong> (W\u01d2 b\u00f9 sh\u00ec l\u01ceosh\u012b)<br>Eu n\u00e3o sou professor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u5979\u4e0d\u662f\u5b66\u751f <\/strong>(T\u0101 b\u00f9 sh\u00ec xu\u00e9sh\u0113ng)<br>Ela n\u00e3o \u00e9 estudante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u4eec\u4e0d\u662f\u533b\u751f<\/strong> (N\u01d0men b\u00f9 sh\u00ec y\u012bsh\u0113ng)<br>Voc\u00eas n\u00e3o s\u00e3o m\u00e9dicos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-forma-interrogativa-de-\u662f-shi\">Forma interrogativa de \u662f (sh\u00ec)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para transformar uma frase com <strong>\u662f<\/strong> (sh\u00ec) em uma pergunta de sim\/n\u00e3o, basta adicionar <strong>\u5417<\/strong> (ma) ao final da frase.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u662f\u5df4\u897f\u4eba\u5417<\/strong>\uff1f(N\u01d0 sh\u00ec B\u0101x\u012b r\u00e9n ma?)<br>Voc\u00ea \u00e9 brasileiro?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u662f\u533b\u751f\u5417\uff1f<\/strong>(T\u0101 sh\u00ec y\u012bsh\u0113ng ma?)<br>Ele \u00e9 m\u00e9dico?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u4eec\u662f\u5b66\u751f\u5417\uff1f<\/strong>(N\u01d0men sh\u00ec xu\u00e9sh\u0113ng ma?)<br>Voc\u00eas s\u00e3o estudantes?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u5979\u662f\u8001\u5e08\u5417\uff1f<\/strong>(T\u0101 sh\u00ec l\u01ceosh\u012b ma?)<br>Ela \u00e9 professora?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-responder-perguntas-com-\u662f-shi\">Como responder perguntas com \u662f (sh\u00ec)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No mandarim, responder perguntas de sim\/n\u00e3o com <strong>\u662f<\/strong> (sh\u00ec) \u00e9 direto e pode ser feito de forma curta ou completa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resposta curta:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u662f\u8001\u5e08\u5417<\/strong>\uff1f(N\u01d0 sh\u00ec l\u01ceosh\u012b ma?)<br>Voc\u00ea \u00e9 professor?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u662f<\/strong> (Sh\u00ec): Sim. \/ <strong>\u4e0d\u662f<\/strong> (B\u00f9 sh\u00ec): N\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para respostas mais completas, repete-se parte da pergunta:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4f60\u662f\u533b\u751f\u5417\uff1f<\/strong>(N\u01d0 sh\u00ec y\u012bsh\u0113ng ma?)<br>Voc\u00ea \u00e9 m\u00e9dico?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u662f\u7684\uff0c\u6211\u662f\u533b\u751f<\/strong> (Sh\u00ec de, w\u01d2 sh\u00ec y\u012bsh\u0113ng)<br>Sim, eu sou m\u00e9dico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4e0d\u662f\uff0c\u6211\u4e0d\u662f\u533b\u751f<\/strong> (B\u00f9 sh\u00ec, w\u01d2 b\u00f9 sh\u00ec y\u012bsh\u0113ng)<br>N\u00e3o, eu n\u00e3o sou m\u00e9dico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quando-nao-usar-\u662f-shi\">Quando n\u00e3o usar \u662f (sh\u00ec)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No mandarim, <strong>\u662f<\/strong> (sh\u00ec) n\u00e3o \u00e9 usado para conectar um sujeito a um adjetivo. Em vez disso, utilizam-se adv\u00e9rbios como <strong>\u5f88<\/strong> (h\u011bn) (muito) ou outros modificadores para descrever caracter\u00edsticas ou estados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No mandarim, os adjetivos funcionam como verbos de estado, ent\u00e3o n\u00e3o precisam do verbo ser para formar a frase. Veja alguns exemplos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u6211\u5f88\u9ad8\u5174<\/strong> (W\u01d2 h\u011bn g\u0101ox\u00ecng)<br>Eu estou feliz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u4ed6\u5f88\u7d2f<\/strong> (T\u0101 h\u011bn l\u00e8i)<br>Ele est\u00e1 cansado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erro comum: \u6211\u662f\u9ad8\u5174 (W\u01d2 sh\u00ec g\u0101ox\u00ecng): Incorreto.<\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background wp-block-paragraph\">No mandarim, \u5f88 (h\u011bn) \u00e9 frequentemente usado antes de adjetivos para formar frases naturais, sem necessariamente significar &#8220;muito&#8221;. Assim, &#8220;\u6211\u5f88\u9ad8\u5174&#8221; pode ser traduzido simplesmente como &#8220;Eu estou feliz&#8221;, ou seja, serve para conectar o sujeito ao adjetivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O verbo \u662f (sh\u00ec) \u00e9 equivalente a &#8220;ser\/estar&#8221; em portugu\u00eas, mas \u00e9 usado exclusivamente para indicar identidade, origem ou equival\u00eancias diretas. Ele n\u00e3o \u00e9 usado para expressar estados tempor\u00e1rios, como &#8220;estar feliz&#8221; ou &#8220;estar cansado&#8221; (esses casos usam outros verbos ou estruturas). \u6211\u662f\u7f8e\u56fd\u4eba (W\u01d2 sh\u00ec m\u011bigu\u00f3 r\u00e9n)Eu sou americano. \u6211\u662f\u5df4\u897f\u4eba (W\u01d2 sh\u00ec B\u0101x\u012b r\u00e9n)Eu sou<\/p>\n","protected":false},"author":1,"featured_media":258,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[8],"class_list":["post-253","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gramatica","tag-verbos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Uso do verbo \u662f (sh\u00ec) &quot;ser\/estar&quot; em mandarim &#8226; Aprender Mandarim<\/title>\n<meta name=\"description\" content=\"O verbo \u662f (sh\u00ec) \u00e9 equivalente a &quot;ser\/estar&quot; em portugu\u00eas, mas \u00e9 usado exclusivamente para indicar identidade, origem ou equival\u00eancias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uso do verbo \u662f (sh\u00ec) &quot;ser\/estar&quot; em mandarim &#8226; Aprender Mandarim\" \/>\n<meta property=\"og:description\" content=\"O verbo \u662f (sh\u00ec) \u00e9 equivalente a &quot;ser\/estar&quot; em portugu\u00eas, mas \u00e9 usado exclusivamente para indicar identidade, origem ou equival\u00eancias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/\" \/>\n<meta property=\"og:site_name\" content=\"Aprender Mandarim\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hridiomas\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-15T19:09:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T15:39:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1205\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hridiomas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hridiomas\" \/>\n<meta name=\"twitter:site\" content=\"@hridiomas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hridiomas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/\"},\"author\":{\"name\":\"hridiomas\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/person\\\/074f113560c2f5d2d8531b6fb060d851\"},\"headline\":\"Uso do verbo \u662f (sh\u00ec) &#8220;ser\\\/estar&#8221; em mandarim\",\"datePublished\":\"2025-01-15T19:09:14+00:00\",\"dateModified\":\"2025-03-24T15:39:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/\"},\"wordCount\":520,\"publisher\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2025\\\/01\\\/destaque-1.jpg\",\"keywords\":[\"verbos\"],\"articleSection\":[\"Gram\u00e1tica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/\",\"name\":\"Uso do verbo \u662f (sh\u00ec) \\\"ser\\\/estar\\\" em mandarim &#8226; Aprender Mandarim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2025\\\/01\\\/destaque-1.jpg\",\"datePublished\":\"2025-01-15T19:09:14+00:00\",\"dateModified\":\"2025-03-24T15:39:18+00:00\",\"description\":\"O verbo \u662f (sh\u00ec) \u00e9 equivalente a \\\"ser\\\/estar\\\" em portugu\u00eas, mas \u00e9 usado exclusivamente para indicar identidade, origem ou equival\u00eancias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2025\\\/01\\\/destaque-1.jpg\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2025\\\/01\\\/destaque-1.jpg\",\"width\":1920,\"height\":1205},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/uso-do-verbo-shi-ser-estar-em-mandarim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uso do verbo \u662f (sh\u00ec) &#8220;ser\\\/estar&#8221; em mandarim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#website\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/\",\"name\":\"Aprender Mandarim\",\"description\":\"Dicas para aprender chin\u00eas\",\"publisher\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#organization\",\"name\":\"HR idiomas\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-hricon.png\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-hricon.png\",\"width\":512,\"height\":512,\"caption\":\"HR idiomas\"},\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hridiomas\",\"https:\\\/\\\/x.com\\\/hridiomas\",\"https:\\\/\\\/www.instagram.com\\\/hridiomas\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2678452\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/HridiomasBr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/#\\\/schema\\\/person\\\/074f113560c2f5d2d8531b6fb060d851\",\"name\":\"hridiomas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/litespeed\\\/avatar\\\/14\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/litespeed\\\/avatar\\\/14\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-mandarim\\\/wp-content\\\/litespeed\\\/avatar\\\/14\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380\",\"caption\":\"hridiomas\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Uso do verbo \u662f (sh\u00ec) \"ser\/estar\" em mandarim &#8226; Aprender Mandarim","description":"O verbo \u662f (sh\u00ec) \u00e9 equivalente a \"ser\/estar\" em portugu\u00eas, mas \u00e9 usado exclusivamente para indicar identidade, origem ou equival\u00eancias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/","og_locale":"pt_BR","og_type":"article","og_title":"Uso do verbo \u662f (sh\u00ec) \"ser\/estar\" em mandarim &#8226; Aprender Mandarim","og_description":"O verbo \u662f (sh\u00ec) \u00e9 equivalente a \"ser\/estar\" em portugu\u00eas, mas \u00e9 usado exclusivamente para indicar identidade, origem ou equival\u00eancias.","og_url":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/","og_site_name":"Aprender Mandarim","article_publisher":"https:\/\/www.facebook.com\/hridiomas","article_published_time":"2025-01-15T19:09:14+00:00","article_modified_time":"2025-03-24T15:39:18+00:00","og_image":[{"width":1920,"height":1205,"url":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-1.jpg","type":"image\/jpeg"}],"author":"hridiomas","twitter_card":"summary_large_image","twitter_creator":"@hridiomas","twitter_site":"@hridiomas","twitter_misc":{"Escrito por":"hridiomas","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/#article","isPartOf":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/"},"author":{"name":"hridiomas","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/person\/074f113560c2f5d2d8531b6fb060d851"},"headline":"Uso do verbo \u662f (sh\u00ec) &#8220;ser\/estar&#8221; em mandarim","datePublished":"2025-01-15T19:09:14+00:00","dateModified":"2025-03-24T15:39:18+00:00","mainEntityOfPage":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/"},"wordCount":520,"publisher":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#organization"},"image":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/#primaryimage"},"thumbnailUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-1.jpg","keywords":["verbos"],"articleSection":["Gram\u00e1tica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/","url":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/","name":"Uso do verbo \u662f (sh\u00ec) \"ser\/estar\" em mandarim &#8226; Aprender Mandarim","isPartOf":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/#primaryimage"},"image":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/#primaryimage"},"thumbnailUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-1.jpg","datePublished":"2025-01-15T19:09:14+00:00","dateModified":"2025-03-24T15:39:18+00:00","description":"O verbo \u662f (sh\u00ec) \u00e9 equivalente a \"ser\/estar\" em portugu\u00eas, mas \u00e9 usado exclusivamente para indicar identidade, origem ou equival\u00eancias.","breadcrumb":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/#primaryimage","url":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-1.jpg","contentUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/uploads\/sites\/14\/2025\/01\/destaque-1.jpg","width":1920,"height":1205},{"@type":"BreadcrumbList","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/uso-do-verbo-shi-ser-estar-em-mandarim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/hridiomas.com\/aprender-mandarim\/"},{"@type":"ListItem","position":2,"name":"Uso do verbo \u662f (sh\u00ec) &#8220;ser\/estar&#8221; em mandarim"}]},{"@type":"WebSite","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#website","url":"https:\/\/hridiomas.com\/aprender-mandarim\/","name":"Aprender Mandarim","description":"Dicas para aprender chin\u00eas","publisher":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hridiomas.com\/aprender-mandarim\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#organization","name":"HR idiomas","url":"https:\/\/hridiomas.com\/aprender-mandarim\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/logo\/image\/","url":"https:\/\/hridiomas.com\/wp-content\/uploads\/2021\/04\/cropped-hricon.png","contentUrl":"https:\/\/hridiomas.com\/wp-content\/uploads\/2021\/04\/cropped-hricon.png","width":512,"height":512,"caption":"HR idiomas"},"image":{"@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hridiomas","https:\/\/x.com\/hridiomas","https:\/\/www.instagram.com\/hridiomas","https:\/\/www.linkedin.com\/company\/2678452","https:\/\/www.youtube.com\/c\/HridiomasBr"]},{"@type":"Person","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/#\/schema\/person\/074f113560c2f5d2d8531b6fb060d851","name":"hridiomas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/litespeed\/avatar\/14\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380","url":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/litespeed\/avatar\/14\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380","contentUrl":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-content\/litespeed\/avatar\/14\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1787959380","caption":"hridiomas"}}]}},"_links":{"self":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/posts\/253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/comments?post=253"}],"version-history":[{"count":0,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/posts\/253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/media\/258"}],"wp:attachment":[{"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/media?parent=253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/categories?post=253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-mandarim\/wp-json\/wp\/v2\/tags?post=253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}