{"id":590,"date":"2016-08-01T14:28:00","date_gmt":"2016-08-01T17:28:00","guid":{"rendered":"https:\/\/hridiomas.com\/aprender-espanhol\/?p=590"},"modified":"2025-02-05T20:34:34","modified_gmt":"2025-02-05T23:34:34","slug":"expressoes-mexicanas-que-voce-precisa-conhecer","status":"publish","type":"post","link":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/","title":{"rendered":"4 express\u00f5es mexicanas que voc\u00ea precisa conhecer"},"content":{"rendered":"\n<p>Muito estudantes de espanhol dizem que quando viajam para o M\u00e9xico tem algumas dificuldades em entender o que as pessoas por l\u00e1 dizem, principalmente quando est\u00e3o falando com amigos mexicanos.<\/p>\n\n\n\n<p>Os estudantes que tiveram a oportunidade de viajar para o M\u00e9xico com a esperan\u00e7a de colocar em pr\u00e1tica seu espanhol, muitas vezes se sentem decepcionados ou frustrados pela impossibilidade de encontrar nos dicion\u00e1rios os significados de muitas das palavras que escutam por l\u00e1.<\/p>\n\n\n\n<p>O M\u00e9xico conta com uma grande parcela da popula\u00e7\u00e3o de l\u00edngua espanhola do mundo, mas o sotaque mexicano \u00e9 bem particular e bem diversificado. Por isso, aqui trazemos algumas palavras que voc\u00ea com certeza encontrar\u00e1 em sua visita ao M\u00e9xico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-guey\">G\u00fcey<\/h2>\n\n\n\n<p>\u00c9 uma palavra muito caracter\u00edstica do M\u00e9xico. Dependendo de quem a utiliza, e em que contexto, <em>g\u00fcey <\/em>tem conota\u00e7\u00f5es que v\u00e3o desde uma palavra de carinho at\u00e9 uma ofensa. Para resumir, \u00e9 o equivalente mexicano ao &#8220;hermano&#8221; (irm\u00e3o) ou &#8220;t\u00edo&#8221; (tio). Por\u00e9m, em outras situa\u00e7\u00f5es e contextos pode querer dizer &#8220;pessoa est\u00fapida&#8221;, &#8220;imbecil&#8221; ou &#8220;idiota&#8221;.<\/p>\n\n\n\n<p>Por conta dessa versatilidade, <em>g\u00fcey <\/em>\u00e9 possivelmente a palavra mais usada em todo M\u00e9xico, e por isso \u00e9 bom conhec\u00ea-la e t\u00ea-la em seu vocabul\u00e1rio. <\/p>\n\n\n\n<p>Exemplos do uso de <em>g\u00fcey<\/em>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Oye g\u00fcey (amigo), v\u00e1monos a la fiesta.<\/li>\n\n\n\n<li>Eres un g\u00fcey (voc\u00ea \u00e9 um idiota), lo echaste a perder.<\/li>\n\n\n\n<li>El g\u00fcey (namorado) de Mar\u00eda Victoria ya se tard\u00f3 mucho, \u00bfno?<\/li>\n\n\n\n<li>\u00bfQu\u00e9 onda g\u00fcey? (Ea\u00ed amigo, como vai?)<\/li>\n\n\n\n<li>G\u00fcey, \u00a1ya la cagu\u00e9!<\/li>\n\n\n\n<li>No seas g\u00fcey, te est\u00e1n poniendo el cuerno.<\/li>\n\n\n\n<li>\u00a1Fue muy g\u00fcey de mi parte no haberte entendido!<\/li>\n\n\n\n<li>Ay g\u00fcey, no tienes los huevos bien puestos.<\/li>\n\n\n\n<li>G\u00fcey, no dejes que tu jefe te explote, no seas g\u00fcey.<\/li>\n\n\n\n<li>Se necesitaron cinco g\u00fceyes para mover el cami\u00f3n.<\/li>\n\n\n\n<li>Muy g\u00fcey, muy g\u00fcey, \u00a1pero bien que te lo cre\u00edste!<\/li>\n\n\n\n<li>Ese g\u00fcey es un huev\u00f3n, seguro no te ayudar\u00e1.<\/li>\n\n\n\n<li>Aqu\u00e9l es medio g\u00fcey, as\u00ed que mejor dile a otro que te ayude.<\/li>\n\n\n\n<li>Hay tanto g\u00fcey desempleado que por eso hay tanta pobreza.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c1ndale<\/h2>\n\n\n\n<p>Muitas pessoas j\u00e1 ouviram em algum momento da vida essa palavra, principalmente aquelas pessoas f\u00e3s de desenhos animados como Looney Tunes, palavra \u00e9 muito conhecida por ser utilizada pelo Speedy Gonz\u00e1lez (conhecido como <a href=\"https:\/\/pt.wikipedia.org\/wiki\/Speedy_Gonz%C3%A1lez\">Ligeirinho<\/a> no Brasil). Isso mesmo, essa \u00e9 a palavra que o Ligeirinho grita todo dia: <em>&#8220;\u00e1ndale \u00e1ndale arriba arriba&#8221;<\/em>.<\/p>\n\n\n\n<p>\u00c1ndale \u00e9 uma palavra cl\u00e1ssica mexicana. Sempre que escutamos essa palavra lembramos do M\u00e9xico e ela deve ser pronunciada com um tom de voz alto e bem agitado. A palavra se traduz essencialmente como um &#8220;vamos logo!&#8221;, &#8220;anda!&#8221;, &#8220;vamos!&#8221;, uma interjei\u00e7\u00e3o. L\u00e1 tamb\u00e9m utilizam o <em>&#8220;Apurate!&#8221;<\/em>, que tem o mesmo significado.<\/p>\n\n\n\n<p>Mas isso n\u00e3o significa que voc\u00ea possa dizer esta palavra quando estiver com um estado de esp\u00edrito calmo. Esta palavra \u00e9 para usar em um estado de \u00e2nimo agitado, em momentos de euforia. <\/p>\n\n\n\n<p>Exemplos do uso de <em>\u00e1ndale<\/em>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00c1ndale, \u00a1vamos al cine!<\/li>\n\n\n\n<li>\u00c1ndale, \u00a1ap\u00farate que ya se me hace tarde!<\/li>\n\n\n\n<li>\u00c1ndale, exactamente como lo imaginaba.<\/li>\n\n\n\n<li>\u00c1ndale, \u00a1la cosa se pone interesante!<\/li>\n\n\n\n<li>\u00a1\u00c1ndale puto que no tengo tu tiempo!<\/li>\n\n\n\n<li>M\u00e1s a la derecha\u2026 un poco m\u00e1s todav\u00eda, \u00a1\u00e1ndale all\u00ed qued\u00f3 bien!<\/li>\n\n\n\n<li>\u00a1\u00c1ndale! \u00a1Qu\u00e9 te deja el cami\u00f3n!<\/li>\n\n\n\n<li>\u00c1ndale cabr\u00f3n, \u00a1as\u00ed quer\u00eda encontrarte!<\/li>\n\n\n\n<li>\u00a1\u00c1ndale! \u00a1tal como me cuentas as\u00ed sucedi\u00f3!<\/li>\n\n\n\n<li>\u00c1ndale, que carro tan chido.<\/li>\n\n\n\n<li>\u00c1ndale r\u00e1pido a comprar lo de la comida.<\/li>\n\n\n\n<li>\u00c1ndale pero que bueno.<\/li>\n\n\n\n<li>\u00c1ndale, \u00a1ese es el ipad que quiero comprarme!<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfA poco?<\/h2>\n\n\n\n<p>\u00c9 uma express\u00e3o de surpresa e incredulidade, em uma situa\u00e7\u00e3o em que voc\u00ea n\u00e3o pode acreditar no que est\u00e3o te dizendo, por exemplo: &#8220;O cantor Julio Iglesias n\u00e3o vai mais se apresentar no M\u00e9xico&#8221;. Resposta: <em>\u00bfA poco?<\/em><\/p>\n\n\n\n<p>Ou, por exemplo: &#8220;O vagabundo que voc\u00ea via todos os dias dando golpes por a\u00ed, ganhou na loteria e agora vive em uma mans\u00e3o&#8221;. Respostas: <em>\u00bfA poco?<\/em>.<\/p>\n\n\n\n<p>\u00c9 uma frase que voc\u00ea diz com espanto no rosto, \u00e9 uma express\u00e3o de surpresa, e de ironia tamb\u00e9m.<\/p>\n\n\n\n<p>Exemplos do uso de <em>\u00bfa poco?<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfA poco se acabaron los boletos?<\/li>\n\n\n\n<li>\u00bfA poco? \u00a1No mames g\u00fcey, no te creo!<\/li>\n\n\n\n<li>\u00bfA poco te mand\u00f3 a la chingada tu novio?<\/li>\n\n\n\n<li>\u00bfA poco hay agua en marte?<\/li>\n\n\n\n<li>\u00bfNo puede ser, a poco te robaron?<\/li>\n\n\n\n<li>Ese g\u00fcey se parece a DiCaprio, \u00bfA poco no?<\/li>\n\n\n\n<li>\u00bfA poco te gust\u00f3 la conferencia?<\/li>\n\n\n\n<li>\u00bfA poco s\u00ed hubo clases?<\/li>\n\n\n\n<li>Soy muy ching\u00f3n, \u00bfA poco no?<\/li>\n\n\n\n<li>Eres muy pendejo, \u00bfA poco no te das cuenta?<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Bronca<\/h2>\n\n\n\n<p>No espanhol &#8220;original&#8221;, a palavra se traduz como &#8220;disputa&#8221;, &#8220;perturba\u00e7\u00e3o&#8221;. Mas os mexicanos d\u00e3o a essa palavra outro significado, que a torna um pouco mais suave. Para os mexicanos, a palavra significa simplesmente &#8220;problema&#8221;, nada de mais\u2026 Quem n\u00e3o tem problemas? Todos temos, mas os mexicanos n\u00e3o se aborrecem com isso. Eles apenas dizem: <em>&#8220;no hay bronca&#8221;<\/em>, isso significa que n\u00e3o tem nenhum problema.<\/p>\n\n\n\n<p>Exemplos do uso de <em>bronca<\/em>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hab\u00eda una bronca en el bar.<\/li>\n\n\n\n<li>Las declaraciones de la se\u00f1ora motivaron la bronca de los asistentes al acto.<\/li>\n\n\n\n<li>Me da mucha bronca que seas as\u00ed de terco.<\/li>\n\n\n\n<li>No hay bronca, \u00a1yo te ayudo!<\/li>\n\n\n\n<li>\u00bfMe est\u00e1s echando bronca?<\/li>\n\n\n\n<li>Sin broncas, la vida es m\u00e1s f\u00e1cil.<\/li>\n\n\n\n<li>\u00a1Tengo muchas broncas econ\u00f3micas!<\/li>\n\n\n\n<li>Bronca tras bronca\u2026 \u00bfNo puedes dejarme en paz?<\/li>\n\n\n\n<li>La bronca est\u00e1 en entender el problema, ya que lo entendiste, no hay bronca para resolverlo.<\/li>\n\n\n\n<li>Te complicas la vida con tantas broncas con tu pareja.<\/li>\n\n\n\n<li>Si quieres bronca, \u00a1la tendr\u00e1s!<\/li>\n\n\n\n<li>\u00a1Se me terminaron las broncas! \u00a1Me divorci\u00e9!<\/li>\n\n\n\n<li>Broncas siempre tendr\u00e1s, lo importante es afrontarlas.<\/li>\n<\/ul>\n\n\n\n<p>Bom, isso \u00e9 tudo por hoje! N\u00e3o \u00e9 nem de longe uma lista completa das express\u00f5es que existem no rico vocabul\u00e1rio mexicano, mas j\u00e1 \u00e9 poss\u00edvel ter uma ideia do que te espera ao visitar o M\u00e9xico.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-dots\"\/>\n\n\n\n<p>Original: <a href=\"https:\/\/www.italki.com\/article\/709\/Palabras-Que-Necesitas-En-Mexico\" target=\"_blank\" rel=\"noreferrer noopener\">Palabras que necesitas en Mexico<\/a> (em espanhol)<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muito estudantes de espanhol dizem que quando viajam para o M\u00e9xico tem algumas dificuldades em entender o que as pessoas por l\u00e1 dizem, principalmente quando est\u00e3o falando com amigos mexicanos. Os estudantes que tiveram a oportunidade de viajar para o M\u00e9xico com a esperan\u00e7a de colocar em pr\u00e1tica seu espanhol, muitas vezes se sentem decepcionados<\/p>\n","protected":false},"author":1,"featured_media":595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[102,113],"class_list":{"0":"post-590","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-expressoes","8":"tag-girias","9":"tag-regionalismos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>4 express\u00f5es mexicanas que voc\u00ea precisa conhecer &#8226; Aprender Espanhol<\/title>\n<meta name=\"description\" content=\"O M\u00e9xico conta com uma grande parcela da popula\u00e7\u00e3o de l\u00edngua espanhola, mas o sotaque mexicano \u00e9 bem particular e bem diversificado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 express\u00f5es mexicanas que voc\u00ea precisa conhecer &#8226; Aprender Espanhol\" \/>\n<meta property=\"og:description\" content=\"O M\u00e9xico conta com uma grande parcela da popula\u00e7\u00e3o de l\u00edngua espanhola, mas o sotaque mexicano \u00e9 bem particular e bem diversificado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/\" \/>\n<meta property=\"og:site_name\" content=\"Aprender Espanhol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hridiomas\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-01T17:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-05T23:34:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hridiomas.com\/aprender-espanhol\/wp-content\/uploads\/sites\/4\/2022\/05\/destaque.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hridiomas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hridiomas\" \/>\n<meta name=\"twitter:site\" content=\"@hridiomas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/\"},\"author\":{\"name\":\"hridiomas\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/#\\\/schema\\\/person\\\/074f113560c2f5d2d8531b6fb060d851\"},\"headline\":\"4 express\u00f5es mexicanas que voc\u00ea precisa conhecer\",\"datePublished\":\"2016-08-01T17:28:00+00:00\",\"dateModified\":\"2025-02-05T23:34:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/\"},\"wordCount\":1018,\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/destaque.jpg\",\"keywords\":[\"g\u00edrias\",\"regionalismos\"],\"articleSection\":[\"Express\u00f5es\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/\",\"name\":\"4 express\u00f5es mexicanas que voc\u00ea precisa conhecer &#8226; Aprender Espanhol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/destaque.jpg\",\"datePublished\":\"2016-08-01T17:28:00+00:00\",\"dateModified\":\"2025-02-05T23:34:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/#\\\/schema\\\/person\\\/074f113560c2f5d2d8531b6fb060d851\"},\"description\":\"O M\u00e9xico conta com uma grande parcela da popula\u00e7\u00e3o de l\u00edngua espanhola, mas o sotaque mexicano \u00e9 bem particular e bem diversificado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/destaque.jpg\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/destaque.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/expressoes-mexicanas-que-voce-precisa-conhecer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 express\u00f5es mexicanas que voc\u00ea precisa conhecer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/#website\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/\",\"name\":\"Aprender Espanhol\",\"description\":\"Dicas para aprender espanhol\",\"alternateName\":\"Espanhol\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/#\\\/schema\\\/person\\\/074f113560c2f5d2d8531b6fb060d851\",\"name\":\"hridiomas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/wp-content\\\/litespeed\\\/avatar\\\/4\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1778697852\",\"url\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/wp-content\\\/litespeed\\\/avatar\\\/4\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1778697852\",\"contentUrl\":\"https:\\\/\\\/hridiomas.com\\\/aprender-espanhol\\\/wp-content\\\/litespeed\\\/avatar\\\/4\\\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1778697852\",\"caption\":\"hridiomas\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"4 express\u00f5es mexicanas que voc\u00ea precisa conhecer &#8226; Aprender Espanhol","description":"O M\u00e9xico conta com uma grande parcela da popula\u00e7\u00e3o de l\u00edngua espanhola, mas o sotaque mexicano \u00e9 bem particular e bem diversificado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/","og_locale":"pt_BR","og_type":"article","og_title":"4 express\u00f5es mexicanas que voc\u00ea precisa conhecer &#8226; Aprender Espanhol","og_description":"O M\u00e9xico conta com uma grande parcela da popula\u00e7\u00e3o de l\u00edngua espanhola, mas o sotaque mexicano \u00e9 bem particular e bem diversificado.","og_url":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/","og_site_name":"Aprender Espanhol","article_publisher":"https:\/\/www.facebook.com\/hridiomas","article_published_time":"2016-08-01T17:28:00+00:00","article_modified_time":"2025-02-05T23:34:34+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-content\/uploads\/sites\/4\/2022\/05\/destaque.jpg","type":"image\/jpeg"}],"author":"hridiomas","twitter_card":"summary_large_image","twitter_creator":"@hridiomas","twitter_site":"@hridiomas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/#article","isPartOf":{"@id":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/"},"author":{"name":"hridiomas","@id":"https:\/\/hridiomas.com\/aprender-espanhol\/#\/schema\/person\/074f113560c2f5d2d8531b6fb060d851"},"headline":"4 express\u00f5es mexicanas que voc\u00ea precisa conhecer","datePublished":"2016-08-01T17:28:00+00:00","dateModified":"2025-02-05T23:34:34+00:00","mainEntityOfPage":{"@id":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/"},"wordCount":1018,"image":{"@id":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/#primaryimage"},"thumbnailUrl":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-content\/uploads\/sites\/4\/2022\/05\/destaque.jpg","keywords":["g\u00edrias","regionalismos"],"articleSection":["Express\u00f5es"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/","url":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/","name":"4 express\u00f5es mexicanas que voc\u00ea precisa conhecer &#8226; Aprender Espanhol","isPartOf":{"@id":"https:\/\/hridiomas.com\/aprender-espanhol\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/#primaryimage"},"image":{"@id":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/#primaryimage"},"thumbnailUrl":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-content\/uploads\/sites\/4\/2022\/05\/destaque.jpg","datePublished":"2016-08-01T17:28:00+00:00","dateModified":"2025-02-05T23:34:34+00:00","author":{"@id":"https:\/\/hridiomas.com\/aprender-espanhol\/#\/schema\/person\/074f113560c2f5d2d8531b6fb060d851"},"description":"O M\u00e9xico conta com uma grande parcela da popula\u00e7\u00e3o de l\u00edngua espanhola, mas o sotaque mexicano \u00e9 bem particular e bem diversificado.","breadcrumb":{"@id":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/#primaryimage","url":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-content\/uploads\/sites\/4\/2022\/05\/destaque.jpg","contentUrl":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-content\/uploads\/sites\/4\/2022\/05\/destaque.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/hridiomas.com\/aprender-espanhol\/expressoes-mexicanas-que-voce-precisa-conhecer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/hridiomas.com\/aprender-espanhol\/"},{"@type":"ListItem","position":2,"name":"4 express\u00f5es mexicanas que voc\u00ea precisa conhecer"}]},{"@type":"WebSite","@id":"https:\/\/hridiomas.com\/aprender-espanhol\/#website","url":"https:\/\/hridiomas.com\/aprender-espanhol\/","name":"Aprender Espanhol","description":"Dicas para aprender espanhol","alternateName":"Espanhol","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hridiomas.com\/aprender-espanhol\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/hridiomas.com\/aprender-espanhol\/#\/schema\/person\/074f113560c2f5d2d8531b6fb060d851","name":"hridiomas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-content\/litespeed\/avatar\/4\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1778697852","url":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-content\/litespeed\/avatar\/4\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1778697852","contentUrl":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-content\/litespeed\/avatar\/4\/fb2620c0c0ccd633ad511be1feb4af56.jpg?ver=1778697852","caption":"hridiomas"}}]}},"_links":{"self":[{"href":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-json\/wp\/v2\/posts\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":0,"href":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-json\/wp\/v2\/posts\/590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-json\/wp\/v2\/media\/595"}],"wp:attachment":[{"href":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-json\/wp\/v2\/media?parent=590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-json\/wp\/v2\/categories?post=590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hridiomas.com\/aprender-espanhol\/wp-json\/wp\/v2\/tags?post=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}